{"id":98253,"date":"2023-10-10T18:26:53","date_gmt":"2023-10-10T21:26:53","guid":{"rendered":"https:\/\/www.centraldenoticias.com.ar\/?p=98253"},"modified":"2023-10-10T18:26:53","modified_gmt":"2023-10-10T21:26:53","slug":"feria-de-artesanos-por-el-dia-la-familia","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2023\/10\/10\/feria-de-artesanos-por-el-dia-la-familia\/","title":{"rendered":"Feria de artesanos por el D\u00eda la Familia"},"content":{"rendered":"<p>La propuesta comenzar\u00e1 el viernes 13 y durar\u00e1 hasta el domingo 15 de octubre. <!--more--><\/p>\n<hr \/>\n<p>La<strong> Plaza Central y el Paseo \u201cJes\u00fas Mend\u00eda\u201d<\/strong> se convertir\u00e1n en una <strong>gran feria de artesanos<\/strong>, durante el<strong> viernes 13, s\u00e1bado 14 y domingo 15 de octubre<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>La propuesta se desarrollar\u00e1 de <strong>09:30 a 20:00 horas,<\/strong> en el marco del <strong>D\u00eda de la Familia.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Participar\u00e1n<strong> artesanos locales<\/strong> que utilizan diferentes t\u00e9cnicas tales como papel mach\u00e9, orfebrer\u00eda, tejido en telar, hilado, encuadernaci\u00f3n, cester\u00eda ecol\u00f3gica, tejido en paja vizcachera, cer\u00e1mica, vitrofusi\u00f3n, marroquiner\u00eda, madera, amigurumis, macram\u00e9, velas, pintura art\u00edstica, bordado, artesan\u00eda reciclada y resignificaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>El objetivo de esta propuesta es impulsar y reconocer la actividad artesanal en el Partido de Olavarr\u00eda, y que a trav\u00e9s de este tipo de eventos se permita brindar un espacio de encuentro y sociabilizaci\u00f3n, generando v\u00ednculos y colaborando a la econom\u00eda social.<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La propuesta comenzar\u00e1 el viernes 13 y durar\u00e1 hasta el domingo 15 de octubre.<\/p>\n","protected":false},"author":6,"featured_media":35904,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,1],"tags":[],"class_list":["post-98253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2021\/10\/Cultura-Feria-artesanos-1-1024x682.jpg?fit=1024%2C682&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/98253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=98253"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/98253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/35904"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=98253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=98253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=98253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}