{"id":91537,"date":"2023-07-29T13:04:49","date_gmt":"2023-07-29T16:04:49","guid":{"rendered":"https:\/\/www.centraldenoticias.com.ar\/?p=91537"},"modified":"2023-07-29T16:30:29","modified_gmt":"2023-07-29T19:30:29","slug":"denunciaron-a-un-hombre-por-traer-a-su-hijo-de-pergamino-a-olavarria-sin-autorizacion-de-su-madre","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2023\/07\/29\/denunciaron-a-un-hombre-por-traer-a-su-hijo-de-pergamino-a-olavarria-sin-autorizacion-de-su-madre\/","title":{"rendered":"Denunciaron a un hombre por traer a su hijo de Pergamino a Olavarr\u00eda sin autorizaci\u00f3n de su madre"},"content":{"rendered":"<p>Seg\u00fan expusieron familiares y amigos, \u201cno ten\u00eda autorizaci\u00f3n de su mam\u00e1 ni de la Justicia\u201d. Se activ\u00f3 un pedido de identificaci\u00f3n y reposici\u00f3n a su familia. El padre argument\u00f3 un presunto maltrato como explicaci\u00f3n al no regreso.<!--more--><\/p>\n<hr \/>\n<p>Una compleja situaci\u00f3n se registr\u00f3 en las \u00faltimas horas en la ciudad: <strong>vecinos de Pergamino denunciaron, en la Justicia y de forma p\u00fablica, que un hombre de 32 a\u00f1os trajo a su hijo de 5 a\u00f1os a Olavarr\u00eda sin autorizaci\u00f3n de la madre ni la Justicia.<\/strong> Se activ\u00f3 un pedido de captura y se logr\u00f3 contactar al hombre qui\u00e9n s<strong>e\u00f1al\u00f3 que el ni\u00f1o sufrir\u00eda una presunta situaci\u00f3n de maltrato.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan se logr\u00f3 saber,<strong> el hombre se llev\u00f3 al ni\u00f1o desde el jard\u00edn de infantes -antes del inicio de las vacaciones de invierno- sin autorizaci\u00f3n ni aviso previo.<\/strong> Tras la denuncia, el <strong>Juzgado de Garant\u00edas N\u00b01 de Pergamino<\/strong> emiti\u00f3 un &#8220;pedido de identificaci\u00f3n y restituci\u00f3n&#8221; contra el hombre de 32 a\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>En paralelo, la mam\u00e1 del ni\u00f1o, amigos y conocidos viralizaron una imagen del hombre en cuesti\u00f3n describiendo la situaci\u00f3n y pidiendo informaci\u00f3n.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><em>\u201cEl viernes 14 de julio \u00b4sustrajo\u00b4 a su hijo de cinco a\u00f1os de la ciudad de Pergamino y lo llev\u00f3 a Olavarr\u00eda. Se encuentra en b\u00fasqueda y captura provincial y federal. Conduce un autom\u00f3vil Volkswagen Voyage oscuro y se encuentra acompa\u00f1ado de su pareja&#8221;<\/em> expresa la publicaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La publicaci\u00f3n concluye pidiendo expl\u00edcita colaboraci\u00f3n a toda persona que pueda brindarle informaci\u00f3n<\/strong>: \u201cPor favor comunicate al 2477635800 o ac\u00e9rcate a la Comisar\u00eda de la Mujer de Olavarr\u00eda o llam\u00e1 al 911&#8243;.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuentes judiciales confirmaron a <strong>Central de Noticias<\/strong> que efectivamente existe un pedido de informaci\u00f3n sobre el paradero del hombre de 32 a\u00f1os. Se agreg\u00f3 que<strong> el hombre habr\u00eda manifestado frente a personal policial que su hijo habr\u00eda sufrido una situaci\u00f3n de maltrato en el \u00e1mbito dom\u00e9stico del entorno de la madre.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>El Juez pergaminense Walter Giuliani deber\u00e1 resolver ahora la situaci\u00f3n procesal del hombre de 32 a\u00f1os<\/strong>, dado que hab\u00eda pedido a efectivos de la Comisar\u00eda de la Mujer local que <em>\u201cidentifiquen y notifiquen al padre de una resoluci\u00f3n de reposici\u00f3n del ni\u00f1o a su progenitora\u201d<\/em> pero el padre habr\u00eda respondido con esta situaci\u00f3n de violencia familiar que complejiza a\u00fan m\u00e1s el caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan expusieron familiares y amigos, \u201cno ten\u00eda autorizaci\u00f3n de su mam\u00e1 ni de la Justicia\u201d. Se activ\u00f3 un pedido de<\/p>\n","protected":false},"author":2,"featured_media":91538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[14,1],"tags":[],"class_list":["post-91537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/07\/juzgado-familia-pergamino.jpg?fit=800%2C530&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/91537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=91537"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/91537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/91538"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=91537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=91537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=91537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}