{"id":87910,"date":"2023-06-17T09:38:23","date_gmt":"2023-06-17T12:38:23","guid":{"rendered":"https:\/\/www.centraldenoticias.com.ar\/?p=87910"},"modified":"2023-06-17T09:39:48","modified_gmt":"2023-06-17T12:39:48","slug":"matrella-entrego-la-mencion-de-interes-legislativo-a-la-jornada-la-ganaderia-que-viene-2023","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2023\/06\/17\/matrella-entrego-la-mencion-de-interes-legislativo-a-la-jornada-la-ganaderia-que-viene-2023\/","title":{"rendered":"Matrella entreg\u00f3 la menci\u00f3n de Inter\u00e9s Legislativo a la jornada &#8220;La Ganader\u00eda que Viene 2023&#8221;"},"content":{"rendered":"<p>&#8220;Sin dudas debemos apoyar estos eventos, principalmente en una ciudad como la nuestra donde la ganader\u00eda ocupa un lugar tan importante en la producci\u00f3n, ya que es uno de los dos partidos con m\u00e1s cabezas de ganado en la Provincia&#8221; expres\u00f3 el concejal del radicalismo local. <!--more--><\/p>\n<hr \/>\n<p>El concejal del radicalismo local,<strong> Sebasti\u00e1n Matrella,<\/strong> entreg\u00f3 la <strong>menci\u00f3n de Inter\u00e9s Legislativo Municipal <\/strong>a la jornada &#8220;<em><strong>La Ganader\u00eda que Viene 2023<\/strong><\/em>&#8220;. Se trata de una propuesta impulsada desde el bloque que compone junto a la edil Bel\u00e9n Vergel.<\/p>\n<p>&nbsp;<\/p>\n<p>La actividad <a href=\"https:\/\/cdnoticias.com\/index.php\/2023\/06\/15\/con-mucho-publico-comenzaron-las-jornadas-la-ganaderia-que-viene\/\" target=\"_blank\" rel=\"noopener\">inici\u00f3 este jueves en el Centro de Convenciones Olavarr\u00eda (CEMO)<\/a> y culmin\u00f3 este viernes en el predio de la Sociedad Rural. El evento est\u00e1 destinado a productores y t\u00e9cnicos relacionados con la producci\u00f3n ganadera, con el objetivo de mantenerlos actualizados sobre diferentes \u00e1reas que hacen a la rentabilidad, eficiencia y sustentabilidad de la actividad. Adem\u00e1s, cuenta con expositores de primer nivel como V\u00edctor Tonelli, Marcos Gim\u00e9nez Zapiola, Gast\u00f3n Britos, Laura Testa, Ricardo Chayer y Natalia Aguilar, entre otros.<\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-87912 size-full\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/06\/IMG-20230615-WA0051.jpg?resize=800%2C587&#038;ssl=1\" alt=\"\" width=\"800\" height=\"587\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/06\/IMG-20230615-WA0051.jpg?w=981&amp;ssl=1 981w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/06\/IMG-20230615-WA0051.jpg?resize=300%2C220&amp;ssl=1 300w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/06\/IMG-20230615-WA0051.jpg?resize=768%2C564&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En este sentido, Matrella expres\u00f3: &#8220;<em><strong>Sin dudas debemos apoyar estos eventos, principalmente en una ciudad como la nuestra donde la ganader\u00eda ocupa un lugar tan importante en la producci\u00f3n, ya que es uno de los dos partidos con m\u00e1s cabezas de ganado en la Provincia&#8221;.<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;El compromiso tiene que estar dado con el medio ambiente y con el bienestar animal, debemos trabajar e impulsar buenas pr\u00e1cticas para ser eficientes&#8221;, cerr\u00f3 Matrella.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Sin dudas debemos apoyar estos eventos, principalmente en una ciudad como la nuestra donde la ganader\u00eda ocupa un lugar tan<\/p>\n","protected":false},"author":6,"featured_media":73453,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,1],"tags":[],"class_list":["post-87910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/12\/hcd-matrella.jpg?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/87910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=87910"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/87910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/73453"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=87910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=87910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=87910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}