{"id":78043,"date":"2023-03-03T08:09:34","date_gmt":"2023-03-03T11:09:34","guid":{"rendered":"https:\/\/www.centraldenoticias.com.ar\/?p=78043"},"modified":"2023-03-03T08:09:34","modified_gmt":"2023-03-03T11:09:34","slug":"la-direccion-nacional-de-migraciones-estara-en-las-oficinas-de-renaper","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2023\/03\/03\/la-direccion-nacional-de-migraciones-estara-en-las-oficinas-de-renaper\/","title":{"rendered":"La Direcci\u00f3n Nacional de Migraciones estar\u00e1 en las oficinas de RENAPER"},"content":{"rendered":"<p>Ser\u00e1 este s\u00e1bado 4 de marzo donde realizar\u00e1n un operativo territorial de manera gratuita. <!--more--><\/p>\n<hr \/>\n<p>El <strong>Registro Nacional de las Personas<\/strong> inform\u00f3 que este<strong> s\u00e1bado 4 de marzo<\/strong> un equipo de la <strong>Direcci\u00f3n Nacional de Migraciones<\/strong> estar\u00e1 en Olavarr\u00eda realizando un abordaje territorial.<\/p>\n<p>&nbsp;<\/p>\n<p>La jornada se llevar\u00e1 a cabo en las <strong>oficinas del RENAPER,<\/strong> ubicada en la calle <strong>Lavalle 3195, de 10:00 a 14:00.<\/strong> Se aclar\u00f3 que<strong> no se realizar\u00e1n tr\u00e1mites de DNI<\/strong> (robo o extrav\u00edo, cambio de domicilio, actualizaciones).<\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78046\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-11.46.58.jpeg?resize=600%2C600&#038;ssl=1\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-11.46.58.jpeg?w=1081&amp;ssl=1 1081w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-11.46.58.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-11.46.58.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-11.46.58.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-11.46.58.jpeg?resize=768%2C768&amp;ssl=1 768w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Los interesados podr\u00e1n recibir asesoramiento, iniciar tr\u00e1mites de Radicaciones, cambios de categor\u00eda (Temporaria a Permanente), emitir y renovar certificados de Residencia Precarias, resolver solicitudes de residencias y consultar estado de tr\u00e1mites de Radicaci\u00f3n ya iniciados.<\/p>\n<p>&nbsp;<\/p>\n<p>Por \u00faltimo se record\u00f3 que <strong>no hay que sacar turno ni pagar nada previamente <\/strong>y que ser\u00e1 por <strong>orden de llegada.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 este s\u00e1bado 4 de marzo donde realizar\u00e1n un operativo territorial de manera gratuita.<\/p>\n","protected":false},"author":6,"featured_media":26958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-78043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2021\/07\/renaper-00-2.jpeg?fit=1280%2C828&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/78043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=78043"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/78043\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/26958"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=78043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=78043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=78043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}