{"id":67899,"date":"2022-10-22T15:38:51","date_gmt":"2022-10-22T18:38:51","guid":{"rendered":"https:\/\/www.centraldenoticias.com.ar\/?p=67899"},"modified":"2022-12-07T15:43:49","modified_gmt":"2022-12-07T18:43:49","slug":"por-la-sequia-cae-la-produccion-de-trigo-en-la-provincia","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2022\/10\/22\/por-la-sequia-cae-la-produccion-de-trigo-en-la-provincia\/","title":{"rendered":"Por la sequ\u00eda, cae la producci\u00f3n de trigo en la Provincia"},"content":{"rendered":"<p>Adem\u00e1s, la falta de precipitaciones y las frecuentes heladas sobre el sudeste de Buenos Aires contin\u00faan condicionando el crecimiento del cultivo y ya se prev\u00e9n mermas en los rendimientos.<!--more--><\/p>\n<hr \/>\n<p><strong>Los productores de trigo del oeste y centro de la provincia de Buenos Aires y norte de La Pampa<\/strong>, donde se concentra m\u00e1s de un 16% de la superficie nacional del cereal de invierno,<strong> dependen de lluvias en el corto plazo<\/strong> que mejoren el escenario del cultivo y amortig\u00fcen las mermas ya esperadas, mientras el 19,4 % de los cuadros se encuentran en plena espigaz\u00f3n, seg\u00fan un informe de la Bolsa de Cereales de Buenos Aires.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n la <strong>falta de precipitaciones<\/strong> y las <strong>frecuentes heladas<\/strong> sobre el sudeste de Buenos Aires contin\u00faan condicionando el crecimiento del cultivo y<strong> ya se prev\u00e9n mermas en los rendimientos<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>La entidad burs\u00e1til indic\u00f3 que \u201ca la fecha, un 15 % de los cuadros se encuentra en plena espigaz\u00f3n\u201d, y agreg\u00f3 que \u201cdicha regi\u00f3n juega un rol clave en el aporte a la producci\u00f3n nacional con una participaci\u00f3n media del 15,2 % del total durante las \u00faltimas cinco campa\u00f1as\u201d.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>En el oeste bonaerense y norte de La Pampa se sembraron 597.000 hect\u00e1reas, en el centro 395.000; en el sudoeste 680.000; en el sudeste 835.000 y en la Cuenca del Salado 48.000 hect\u00e1reas.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <em>Agencia DIB<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s, la falta de precipitaciones y las frecuentes heladas sobre el sudeste de Buenos Aires contin\u00faan condicionando el crecimiento del<\/p>\n","protected":false},"author":4,"featured_media":67900,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,1],"tags":[],"class_list":["post-67899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/10\/DIB-trigo.jpg?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/67899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=67899"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/67899\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/67900"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=67899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=67899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=67899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}