{"id":62643,"date":"2022-08-18T11:13:40","date_gmt":"2022-08-18T14:13:40","guid":{"rendered":"https:\/\/www.centraldenoticias.com.ar\/?p=62643"},"modified":"2022-08-18T12:28:32","modified_gmt":"2022-08-18T15:28:32","slug":"por-medidas-gremiales-suspenden-atencion-en-licencias-de-conducir-en-la-maxima","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2022\/08\/18\/por-medidas-gremiales-suspenden-atencion-en-licencias-de-conducir-en-la-maxima\/","title":{"rendered":"Por medidas gremiales, suspenden atenci\u00f3n en Licencias de Conducir en La M\u00e1xima"},"content":{"rendered":"<p>As\u00ed fue informado desde el Municipio. El Sindicato de Municipales permanece en \u201cestado de asamblea permanente y movilizaci\u00f3n\u201d. Reclaman el cumplimiento de medidas de seguridad e higiene en el Hospital.<!--more--><\/p>\n<hr \/>\n<p>Este jueves el Municipio inform\u00f3 que debido a las medidas gremiales adoptadas por el Sindicato de Trabajadores Municipales, <strong>se suspendi\u00f3 la atenci\u00f3n de las pruebas de Licencias de Conducir en La M\u00e1xima.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Asimismo, se\u00f1alaron que para realizar la reprogramaci\u00f3n de turnos deber\u00e1n comunicarse al <strong>WhatsApp 2284230610.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Recordemos que el <a href=\"https:\/\/cdnoticias.com\/index.php\/2022\/08\/12\/el-sindicato-de-trabajadores-municipales-declaro-estado-de-asamblea-permanente-y-movilizacion\/\" target=\"_blank\" rel=\"noopener\">pasado viernes<\/a> el gremio declar\u00f3 <strong>\u201cestado de asamblea permanente y movilizaci\u00f3n\u201d<\/strong> en reclamo por el cumplimiento de medidas de seguridad e higiene en el Hospital Municipal.<\/p>\n<p>&nbsp;<\/p>\n<p>Solicitaron al Intendente de la provisi\u00f3n de calzado y ropa de trabajo, denunciando que ya se \u201chan producido accidentes graves entre el personal por esa carencia\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed fue informado desde el Municipio. El Sindicato de Municipales permanece en \u201cestado de asamblea permanente y movilizaci\u00f3n\u201d. Reclaman el<\/p>\n","protected":false},"author":5,"featured_media":62644,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-62643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/08\/STMO.jpg?fit=768%2C432&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/62643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=62643"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/62643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/62644"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=62643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=62643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=62643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}