{"id":53330,"date":"2022-05-01T19:00:35","date_gmt":"2022-05-01T22:00:35","guid":{"rendered":"https:\/\/www.centraldenoticias.com.ar\/?p=53330"},"modified":"2022-05-01T20:12:11","modified_gmt":"2022-05-01T23:12:11","slug":"las-mejores-imagenes-de-la-vuelta-al-municipio-2022","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2022\/05\/01\/las-mejores-imagenes-de-la-vuelta-al-municipio-2022\/","title":{"rendered":"Las mejores im\u00e1genes de la Vuelta al Municipio 2022"},"content":{"rendered":"<p>Con la novedad de la realizaci\u00f3n de una media marat\u00f3n, Central de Deportes realiz\u00f3 una completa cobertura de todo lo acontecido fuera del Palacio San Mart\u00edn. <!--more--><\/p>\n<hr \/>\n<p>Tras dos a\u00f1os de ausencia y con la novedad de los 21K <strong>se corri\u00f3 la 33\u00b0 edici\u00f3n de la \u201cVuelta al Municipio\u201d que tuvo a Gustavo Fern\u00e1ndez como principal protagonista consagr\u00e1ndose en la Media Marat\u00f3n con un tiempo de 1.06.52<\/strong>, segundo fue Ulises Sanguinetti de Tres Arroyos con 1.08.47, tercero Sergio Hoffmann (Tandil) con 1.10.23, cuarto Osvaldo Barreto (General Villegas) y quinto Ezequiel Magallanes (Olavarr\u00eda) con 1.15.44.<\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-53333\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/05\/vuelta-al-muni-2-960x640_c.jpg?resize=800%2C533&#038;ssl=1\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/05\/vuelta-al-muni-2-960x640_c.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/05\/vuelta-al-muni-2-960x640_c.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/05\/vuelta-al-muni-2-960x640_c.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/05\/vuelta-al-muni-2-960x640_c.jpg?resize=272%2C182&amp;ssl=1 272w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>Adem\u00e1s hubo un millar de competidores que en sus diferentes categor\u00edas participaron de esta important\u00edsima edici\u00f3n.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>En<a href=\"http:\/\/centraldeportes.com.ar\/vuelta-al-municipio-gustavo-fernandez-y-lujan-urrutia-los-ganadores-de-los-21k\/\" target=\"_blank\" rel=\"noopener\"> Central de Deportes podr\u00e1s vivir la cobertura tanto en lo deportivo<\/a> como as\u00ed tambi\u00e9n en <a href=\"http:\/\/centraldeportes.com.ar\/las-mejores-fotos-de-la-prueba-pedestre-mas-importante-de-olavarria\/\" target=\"_blank\" rel=\"noopener\">calidad de im\u00e1genes en cada uno de estos enlaces.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la novedad de la realizaci\u00f3n de una media marat\u00f3n, Central de Deportes realiz\u00f3 una completa cobertura de todo lo<\/p>\n","protected":false},"author":2,"featured_media":53331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-53330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/05\/vuelta-al-muni_2-2.jpg?fit=1280%2C853&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/53330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=53330"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/53330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/53331"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=53330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=53330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=53330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}