{"id":24305,"date":"2021-06-18T10:06:18","date_gmt":"2021-06-18T13:06:18","guid":{"rendered":"http:\/\/www.centraldenoticias.com.ar\/?p=24305"},"modified":"2021-06-18T10:06:18","modified_gmt":"2021-06-18T13:06:18","slug":"piden-prioridad-para-vacunar-a-ninos-con-sindrome-de-down-y-otros-grupos","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2021\/06\/18\/piden-prioridad-para-vacunar-a-ninos-con-sindrome-de-down-y-otros-grupos\/","title":{"rendered":"Piden \u201cprioridad\u201d para vacunar a ni\u00f1os con s\u00edndrome de down y otros grupos"},"content":{"rendered":"<p>Entre los grupos solicitados, se encuentran los cuidadores de personas con discapacidad. El proyecto fue presentado por el senador Alejandro Cellillo.\u00a0<!--more--><\/p>\n<hr \/>\n<p>El vicepresidente segundo del Senado, <strong>Alejandro Cellillo, present\u00f3 un proyecto en la c\u00e1mara alta provincial para que el gobierno de Kicillof disponga la incorporaci\u00f3n, dentro de los grupos prioritarios del plan de vacunaci\u00f3n provincial, a quienes conviven y\/o cuidan a personas con discapacidad y a los ni\u00f1os y ni\u00f1as de entre 12 y 18 a\u00f1os con S\u00edndrome de Down.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>El senador de la Uni\u00f3n C\u00edvica Radical solicit\u00f3 al Ejecutivo bonaerense vacunar a<strong> personas con S\u00edndrome de Down entre 12 y 18 a\u00f1os<\/strong>, teniendo en cuenta que<em> &#8220;diversos estudios publicados dan cuenta de que las personas con S\u00edndrome de Down son m\u00e1s susceptibles a desarrollar los s\u00edntomas m\u00e1s severos de Covid-19&#8221;.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>El legislador alvearense adem\u00e1s inform\u00f3 que<strong><em> &#8220;como es de p\u00fablico conocimiento se ha incorporado a las personas mayores de 18 a\u00f1os con discapacidad dentro de los grupos prioritarios&#8221;<\/em><\/strong>, a lo que a\u00f1adi\u00f3: <em>&#8220;Por eso creemos que es fundamental inmunizar a las personas que los cuidan y conviven&#8221;.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre los grupos solicitados, se encuentran los cuidadores de personas con discapacidad. El proyecto fue presentado por el senador Alejandro<\/p>\n","protected":false},"author":2,"featured_media":9230,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,1],"tags":[],"class_list":["post-24305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2020\/12\/Cellillo-Vice.jpeg?fit=1024%2C682&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/24305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=24305"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/24305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/9230"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=24305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=24305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=24305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}