{"id":24303,"date":"2021-06-18T09:51:57","date_gmt":"2021-06-18T12:51:57","guid":{"rendered":"http:\/\/www.centraldenoticias.com.ar\/?p=24303"},"modified":"2021-06-18T09:51:57","modified_gmt":"2021-06-18T12:51:57","slug":"clotilde-elena-villa-bastianello-viuda-de-massaro-tilde-q-e-p-d","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2021\/06\/18\/clotilde-elena-villa-bastianello-viuda-de-massaro-tilde-q-e-p-d\/","title":{"rendered":"Clotilde Elena Villa Bastianello viuda de Massaro \u201cTilde\u201d (Q.E.P.D.)"},"content":{"rendered":"<p>Falleci\u00f3 en Olavarr\u00eda el d\u00eda 18 de junio de 2021 a los 102 a\u00f1os de edad.<\/p>\n<p>&nbsp;<\/p>\n<p>Sus hijos: Mar\u00eda Rosa, Juan Carlos, Osvaldo, Mar\u00eda Elena, Ricardo y Ra\u00fal; sus hijos pol\u00edticos; sus nietos; sus bisnietos y dem\u00e1s deudos participan su fallecimiento.<\/p>\n<p>&nbsp;<\/p>\n<p>Sin velatorio. Responso: Cementerio Municipal de Olavarr\u00eda. Inhumaci\u00f3n: Cementerio Municipal de Olavarr\u00eda, viernes 18 a las 11 horas. Servicio adherido a Coopelectric.<\/p>\n<p>&nbsp;<\/p>\n<p>Barrio en el que viv\u00eda: Jard\u00edn<\/p>\n<p>&nbsp;<\/p>\n<p>Lugar de nacimiento: Sierra Chica<\/p>\n<p>&nbsp;<\/p>\n<p>Actividad que desarrollaba: Jubilada y pensionada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Falleci\u00f3 en Olavarr\u00eda el d\u00eda 18 de junio de 2021 a los 102 a\u00f1os de edad. &nbsp; Sus hijos: Mar\u00eda<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-24303","post","type-post","status-publish","format-standard","hentry","category-necrologicas"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/24303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=24303"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/24303\/revisions"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=24303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=24303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=24303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}