{"id":208654,"date":"2026-07-15T08:52:40","date_gmt":"2026-07-15T11:52:40","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=208654"},"modified":"2026-07-15T08:52:42","modified_gmt":"2026-07-15T11:52:42","slug":"giro-recupero-mas-de-138-mil-kilos-de-materiales-reciclables-durante-el-primer-semestre","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2026\/07\/15\/giro-recupero-mas-de-138-mil-kilos-de-materiales-reciclables-durante-el-primer-semestre\/","title":{"rendered":"GIRO recuper\u00f3 m\u00e1s de 138 mil kilos de materiales reciclables durante el primer semestre"},"content":{"rendered":"\n<p>La recolecci\u00f3n diferenciada concentr\u00f3 la mayor cantidad de materiales recuperados. El Municipio destac\u00f3 el trabajo conjunto con la Cooperativa Viento en Contra y las acciones para fortalecer la separaci\u00f3n en origen.<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p>El programa de <strong>Gesti\u00f3n Integral de Residuos de Olavarr\u00eda (GIRO),<\/strong> impulsado por el Municipio a trav\u00e9s de la Coordinaci\u00f3n de Ambiente de la Secretar\u00eda de Desarrollo Econ\u00f3mico y Productivo,<strong> recuper\u00f3 138.640 kilogramos de materiales reciclables durante el primer semestre del a\u00f1o<\/strong>, como resultado de las distintas herramientas que integran el <strong>sistema de separaci\u00f3n y reciclaje.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>El programa funciona en la ciudad desde hace m\u00e1s de cinco a\u00f1os y, desde 2024, la Cooperativa Viento en Contra tiene a su cargo la recolecci\u00f3n diferenciada y la operaci\u00f3n de la Planta de Clasificaci\u00f3n. <\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>Desde el Municipio se\u00f1alaron que el trabajo conjunto permiti\u00f3 <strong>fortalecer el sistema de recuperaci\u00f3n de materiales<\/strong> mediante la prestaci\u00f3n del servicio y las tareas de concientizaci\u00f3n desarrolladas en distintos barrios.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Del total recuperado durante los primeros seis meses del a\u00f1o, 101.720 kilogramos correspondieron a la recolecci\u00f3n diferenciada del programa GIRO, 27.769 kilogramos fueron aportados a trav\u00e9s de los Ecopuntos distribuidos en distintos sectores de la ciudad, 8.278 kilogramos provinieron de grandes generadores y 873 kilogramos se recuperaron en las jornadas de &#8220;Tu Barrio Recicla&#8221;.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>Asimismo, la gacetilla oficial se\u00f1ala que durante 2025<strong> el programa acumula m\u00e1s de 197.000 kilogramos de residuos reciclables recuperados,<\/strong> consolidando el crecimiento de la separaci\u00f3n en origen en la ciudad.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Desde el Municipio destacaron que estos resultados son posibles gracias al compromiso de vecinos, instituciones, comercios y empresas que separan sus residuos para que los materiales puedan reincorporarse al circuito productivo.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>En ese marco, tambi\u00e9n se puso en valor el trabajo territorial de las <strong>promotoras ambientales de la Cooperativa Viento en Contra,<\/strong> quienes recorren diariamente los barrios brindando informaci\u00f3n sobre el programa y acompa\u00f1ando a los vecinos en la incorporaci\u00f3n de h\u00e1bitos de separaci\u00f3n de residuos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Durante el semestre, adem\u00e1s,<strong> se realizaron 10 jornadas de &#8220;Tu Barrio Recicla&#8221;<\/strong>, destinadas a los sectores que todav\u00eda no cuentan con el servicio de recolecci\u00f3n diferenciada. Paralelamente, el Municipio llev\u00f3 adelante la <strong>relocalizaci\u00f3n de los Ecopuntos del Partido<\/strong> con el objetivo de mejorar su distribuci\u00f3n y facilitar el acceso de la comunidad a esta herramienta de reciclaje.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Por \u00faltimo, se inform\u00f3 que <strong>contin\u00faan las acciones de concientizaci\u00f3n<\/strong> en los distintos recorridos de recolecci\u00f3n diferenciada y que pr\u00f3ximamente se desarrollar\u00e1 una nueva intervenci\u00f3n territorial junto a las promotoras ambientales para seguir fortaleciendo la separaci\u00f3n en origen y la participaci\u00f3n de la comunidad.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La recolecci\u00f3n diferenciada concentr\u00f3 la mayor cantidad de materiales recuperados. El Municipio destac\u00f3 el trabajo conjunto con la Cooperativa Viento<\/p>\n","protected":false},"author":6,"featured_media":208656,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,7],"tags":[],"class_list":["post-208654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-central"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2026\/07\/giro-ecopunto.jpg?fit=900%2C549&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/208654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=208654"}],"version-history":[{"count":4,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/208654\/revisions"}],"predecessor-version":[{"id":208663,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/208654\/revisions\/208663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/208656"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=208654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=208654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=208654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}