{"id":204797,"date":"2026-05-29T21:12:34","date_gmt":"2026-05-30T00:12:34","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=204797"},"modified":"2026-05-30T12:19:52","modified_gmt":"2026-05-30T15:19:52","slug":"dos-allanamientos-positivos-y-una-detencion-por-dos-robos-cometidos-en-una-misma-vivienda","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2026\/05\/29\/dos-allanamientos-positivos-y-una-detencion-por-dos-robos-cometidos-en-una-misma-vivienda\/","title":{"rendered":"Dos allanamientos positivos y una detenci\u00f3n por dos robos cometidos en una misma vivienda"},"content":{"rendered":"\n<p>Los procedimientos fueron realizados por personal de la SubDDI Olavarr\u00eda en dos domicilios de la ciudad. El acusado fue trasladado a la Unidad Penitenciaria N\u00ba 2 de Sierra Chica.<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p>Personal del <strong>Grupo Operativo de la SubDDI Olavarr\u00eda llev\u00f3 adelante d\u00edas atr\u00e1s allanamientos en dos viviendas ubicadas dentro del casco urbano de la ciudad,<\/strong> en el marco de una investigaci\u00f3n por <strong>dos hechos de robo cometidos en un mismo domicilio y atribuidos al mismo autor.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>De acuerdo con la informaci\u00f3n oficial,<strong> los procedimientos arrojaron resultados positivos para la pesquisa. <\/strong>En paralelo, el magistrado interviniente libr\u00f3 una orden de detenci\u00f3n para el presunto autor de los hechos investigados.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La causa se encuentra a cargo de la UFI N\u00ba 4 y del Juzgado de Garant\u00edas N\u00ba 2.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Tras concretarse la detenci\u00f3n,<strong> el acusado fue trasladado a la sede de la SubDDI Olavarr\u00eda para el cumplimiento de los recaudos legales correspondientes. <\/strong>Posteriormente, fue derivado a la Unidad Penitenciaria N\u00ba 2 de Sierra Chica, donde qued\u00f3 alojado a disposici\u00f3n de la Justicia mientras contin\u00faa el proceso judicial.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los procedimientos fueron realizados por personal de la SubDDI Olavarr\u00eda en dos domicilios de la ciudad. El acusado fue trasladado<\/p>\n","protected":false},"author":2,"featured_media":204798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[14,1],"tags":[],"class_list":["post-204797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-29-at-16.22.58-e1780099939352.jpeg?fit=1507%2C885&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/204797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=204797"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/204797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/204798"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=204797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=204797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=204797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}