{"id":204746,"date":"2026-05-29T13:30:31","date_gmt":"2026-05-29T16:30:31","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=204746"},"modified":"2026-05-29T16:30:17","modified_gmt":"2026-05-29T19:30:17","slug":"el-operativo-frio-se-extendio-hasta-el-5-de-junio","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2026\/05\/29\/el-operativo-frio-se-extendio-hasta-el-5-de-junio\/","title":{"rendered":"El Operativo Fr\u00edo se extendi\u00f3 hasta el 5 de junio"},"content":{"rendered":"<p>Se trata de un circuito de solidaridad, coordinado por la Municipalidad de Olavarr\u00eda con la participaci\u00f3n de 40 instituciones, que permite contar con distintos sitios de recepci\u00f3n de ropa de abrigo, frazadas y calzados.<\/p>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>El Municipio de Olavarr\u00eda inform\u00f3 que<strong> se extendi\u00f3 el plazo hasta el pr\u00f3ximo viernes 5 de junio<\/strong> para la<strong> recepci\u00f3n de donaciones del \u201cOperativo Fr\u00edo\u201d<\/strong>, el dispositivo encabezado desde el Municipio y que cuenta con la colaboraci\u00f3n y participaci\u00f3n activa de alrededor de<strong> 40 instituciones de todo el Partido<\/strong> para poder acompa\u00f1ar y asistir a <strong>personas en situaci\u00f3n de vulnerabilidad ante las bajas temperaturas<\/strong>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Se trata de un circuito de solidaridad que permite contar con<strong> sitios de recepci\u00f3n de ropas de abrigo, frazadas y calzados <\/strong>que posteriormente ser\u00e1n entregados en una jornada cuya fecha y sedes se informar\u00e1n pr\u00f3ximamente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Se record\u00f3 que en esta primera etapa del \u201cOperativo Fr\u00edo\u201d est\u00e1 destinada \u00fanicamente a la recolecci\u00f3n y acopio de donaciones. Se pidi\u00f3 que acerquen cada elemento en condiciones de uso, limpios y secos.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>Posteriormente, se avanzar\u00e1 con la <strong>centralizaci\u00f3n, selecci\u00f3n y clasificaci\u00f3n de prendas<\/strong>, para luego <strong>articular con la realizaci\u00f3n de una jornada solidaria <\/strong>en la que se llevar\u00e1 a cabo la entrega, con fecha y sedes a confirmar.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-central-de-noticias-olavarr-a wp-block-embed-central-de-noticias-olavarr-a\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"5RsWMqXPUa\"><a href=\"https:\/\/cdnoticias.com\/index.php\/2026\/05\/27\/leo-yunger-encaramos-un-invierno-con-una-situacion-social-que-es-mas-compleja-que-la-del-invierno-pasado\/\">Leo Yunger: \u201cEncaramos un invierno con una situaci\u00f3n social que es m\u00e1s compleja que la del invierno pasado\u201d<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;Leo Yunger: \u201cEncaramos un invierno con una situaci\u00f3n social que es m\u00e1s compleja que la del invierno pasado\u201d&#8221; &#8212; Central de Noticias | Olavarr\u00eda\" src=\"https:\/\/cdnoticias.com\/index.php\/2026\/05\/27\/leo-yunger-encaramos-un-invierno-con-una-situacion-social-que-es-mas-compleja-que-la-del-invierno-pasado\/embed\/#?secret=2OJGZv6887#?secret=5RsWMqXPUa\" data-secret=\"5RsWMqXPUa\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lugares donde acercar las donaciones<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>En Olavarr\u00eda<\/strong><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Club Pueblo Nuevo. Lunes a Viernes 9 a 12 y 14 a 20 horas.<br>Club \u00c1lvaro Barros. Todos los d\u00edas de 10: 30 a 15 horas<br>Club Ferro. Lunes a viernes de 8 a 12 hs y de 15 a 19 horas<br>Sociedad de Fomento Mariano Moreno. Lunes a viernes de 10 a 13 hs y de 17 a 20 horas (por calle Espa\u00f1a).<br>Club Embajadores. Lunes a viernes de 15 hs a 19 horas<br>Racing Club. Lunes a viernes 9 a 19 horas (en la Secretar\u00eda)<br>Club El Provincial. Lunes, mi\u00e9rcoles y viernes de 16 a 19 horas.<br>Club El Fort\u00edn. Lunes a viernes de 9 a 11 y 16 a 18 horas (Predio Av. Pellegrini)<br>Cuartel Central de Bomberos. Lunes a viernes de 17 a 20 horas<br>Iglesia \u201cEl Dios de lo Imposible\u201d. Mi\u00e9rcoles y viernes de 9 a 12 horas. Balcarce 4768.<br>Iglesia de Jesucristo. Martes y s\u00e1bado de 9 a 12 horas. Berutti 1105.<br>Iglesia \u201cAguas Profundas\u201d. Martes de 10 a 13 horas, jueves de 14 a 17 horas. Laprida 3039.<br>Facultad de Ciencias Sociales. Lunes a viernes 9 a 17 horas.<br>Facultad de Ingenier\u00eda. Lunes a viernes 9 a 17 horas.<br>Facultad de Ciencias de la Salud. Lunes a viernes 9 a 17 horas.<br>Escuela Nacional P\u00e9rez Esquivel. Lunes a viernes 9 a 17 horas.<br>Colegio Rosario. Lunes a viernes de 8 a 12, de 13 a 17 y de 18 a 20 horas.<br>Colegio Nuestra Se\u00f1ora de F\u00e1tima. Lunes a viernes de 8 a 12 y de 13 a 17 horas.<br>CEF 44 en Barrio CECO. Lunes a viernes de 16:30 a 20:30 horas.<br>Escuela Secundaria N\u00ba 10 (Ex Normal). Lunes a viernes de 13 a 17 horas.<br>Escuela Primaria N\u00ba 51. Lunes a viernes de 8 a 12 y de 13 a 17 horas.<br>Escuela Primaria N\u00ba 4. Lunes a viernes de 8 a 12 y de 13 a 17 horas.<br>Escuela Primaria N\u00ba 50. Lunes a viernes de 8 a 12 y de 13 a 17 horas.<br>Escuela Primaria N\u00ba 76. Lunes a viernes de 7:30 a 12:30 y de 13 a 18 horas.<br>Escuela Secundaria N\u00ba 1. Lunes a viernes de de 8 a 12, de 13 a 17 y de 18 a 20 horas.<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>En Loma Negra<\/strong><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Club Loma Negra. Lunes a jueves de 9 a 12 horas y de 17 a 19 horas (en la Secretar\u00eda).<br>Destacamento de Bomberos Loma Negra. Lunes a viernes de 17 a 20 horas.<br>Centro Madre Teresa de Calcuta. Lunes a viernes de 8 a 12 y de 13 a 17 horas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>En Sierras Bayas<\/strong><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Club San Mart\u00edn. Lunes a viernes de 8 a 12 horas.<br>Destacamento de Bomberos Sierras Bayas. Lunes a viernes de 17 a 20 horas<br>Instituto Privado de Sierras Bayas. Lunes a viernes de 13 a 17 horas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>En Hinojo<\/strong><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Club Atl\u00e9tico Hinojo. Lunes a viernes de 10 a 12 y de 17 a 20 horas.<br>Destacamento de Bomberos Hinojo Lunes a viernes de 17 a 20 horas.<br>Escuela Primaria N\u00ba 11. Lunes a viernes de 8 a 12 horas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>En Sierra Chica<\/strong><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Club Sierra Chica. Lunes a viernes de 15:30 hs a 19:00 horas. (Estadio \u201cPedro Iriart Legorburu\u201d)<br>Centro Educativo Complementario en Sierra Chica. Lunes a viernes de 8 a 17 horas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>En Espigas<\/strong><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Escuela Secundaria N\u00ba 15 en Espigas de lunes a viernes de 13 a 18 horas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>En Santa Luisa<\/strong><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Escuela Secundaria N\u00ba 23 en Santa Luisa de lunes a viernes de 12 a 18 horas.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de un circuito de solidaridad, coordinado por la Municipalidad de Olavarr\u00eda con la participaci\u00f3n de 40 instituciones, que<\/p>\n","protected":false},"author":4,"featured_media":117151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-204746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/frio-estacion-invierno-otono-DIB.jpeg?fit=696%2C475&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/204746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=204746"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/204746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/117151"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=204746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=204746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=204746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}