{"id":204725,"date":"2026-05-29T11:06:04","date_gmt":"2026-05-29T14:06:04","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=204725"},"modified":"2026-05-29T16:06:24","modified_gmt":"2026-05-29T19:06:24","slug":"desde-el-lunes-aumentan-la-luz-y-el-gas-para-los-usuarios-de-olavarria","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2026\/05\/29\/desde-el-lunes-aumentan-la-luz-y-el-gas-para-los-usuarios-de-olavarria\/","title":{"rendered":"Desde el lunes, aumentan la luz y el gas para los usuarios de Olavarr\u00eda"},"content":{"rendered":"<p>A partir de junio habr\u00e1 suba de electricidad en dos tramos, de acuerdo al consumo y la inclusi\u00f3n de subsidios. Para el servicio de gas, el incremento ser\u00e1 de 5% en el cargo fijo y de casi 2 puntos en el cargo variable.<\/p>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>El Gobierno bonaerense <strong>aprob\u00f3 nuevos cuadros tarifarios para las distribuidoras el\u00e9ctricas <\/strong>de la <strong>provincia de Buenos Aires<\/strong>, incorporando los <strong>precios mayoristas definidos por la Secretar\u00eda de Energ\u00eda de la Naci\u00f3n<\/strong> y una <strong>actualizaci\u00f3n transitoria<\/strong> del <strong>Valor Agregado de Distribuci\u00f3n (VAD)<\/strong>, que comenzar\u00e1 a regir <strong>desde el 1\u00b0 de junio de 2026<\/strong>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>La medida alcanza a EDELAP, EDEA, EDEN y EDES, e impactar\u00e1 en las 200 cooperativas el\u00e9ctricas del interior bonaerense, entre ellas Coopelectric con lo que los usuarios de Olavarr\u00eda quedan encuadrados en la suba tarifaria.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>La resoluci\u00f3n fue publicada este viernes en el<strong> Bolet\u00edn Oficial <\/strong>y se apoya en el rec\u00e1lculo realizado por el <strong>Organismo de Control de Energ\u00eda El\u00e9ctrica de la Provincia de Buenos Aires (OCEBA)<\/strong>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Seg\u00fan el texto oficial que analiz\u00f3 Agencia DIB, el cargo fijo aumentar\u00e1 en dos tramos entre un 6% y 7%, de acuerdo al consumo. Mientras que el cargo variable trepar\u00e1 en torno al 8%, siempre para aquellos usuarios residenciales sin subsidio. En cambio, aquellos que est\u00e1n beneficiados por el r\u00e9gimen de Subsidios Energ\u00e9ticos Focalizados (SEF) tendr\u00e1n un salto en la tarifa mayor: el cargo fijo trepar\u00e1 en las dos etapas un 7,5% mientras que el cargo variable de la factura un 11%.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>Los nuevos cuadros <strong>incorporan los precios estacionales de energ\u00eda y potencia mayorista<\/strong> establecidos por la Resoluci\u00f3n 109\/2026 de la Secretar\u00eda de Energ\u00eda nacional para el <strong>per\u00edodo mayo-julio de 2026<\/strong>, adem\u00e1s de los costos de transporte y del Fondo Nacional de la Energ\u00eda El\u00e9ctrica (FNEE).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tarifas de luz con subsidios<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>La resoluci\u00f3n tambi\u00e9n mantiene el <strong>esquema de subsidios energ\u00e9ticos focalizados<\/strong> dispuesto por el Decreto nacional 943\/2025. De esta manera, <strong>seguir\u00e1n vigentes las bonificaciones para usuarios residenciales beneficiarios del SEF, tarifa social, clubes de barrio y entidades de bien p\u00fablico<\/strong>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En el caso de los <strong>usuarios residenciales subsidiados, el tope de consumo bonificado continuar\u00e1 siendo de 300 kWh mensuales durante mayo, junio y julio<\/strong>. El <strong>excedente<\/strong> por encima de ese l\u00edmite se abonar\u00e1 <strong>sin subsidio<\/strong>. En este caso puntual, la Resoluci\u00f3n 109 fij\u00f3 esa <strong>bonificaci\u00f3n adicional en un 10,67% <\/strong>sobre el consumo base para esos tres meses. Pero <strong>el beneficio \u201cse va reduciendo mes a mes\u201d<\/strong> con el objetivo de avanzar en la reestructuraci\u00f3n del esquema de subsidios energ\u00e9ticos y dar previsibilidad a las facturas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Adem\u00e1s, el Gobierno provincial autoriz\u00f3 <strong>desde junio una actualizaci\u00f3n transitoria del VAD<\/strong>, del Sobrecosto por Generaci\u00f3n Local (SGL), del Agregado Tarifario y del Cargo Transici\u00f3n Tarifaria (CTT), en el marco de la etapa de transici\u00f3n tarifaria vigente hasta la implementaci\u00f3n de una nueva revisi\u00f3n tarifaria integral.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La norma tambi\u00e9n actualiza las <strong>compensaciones destinadas a distribuidoras receptoras del Fondo Provincial de Compensaciones Tarifarias <\/strong>y ratifica beneficios espec\u00edficos para clubes de barrio, entidades sin fines de lucro y usuarios alcanzados por tarifa social.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aumentos del gas<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Por otra parte, el<strong> Ente Nacional Regulador del Gas y la Electricidad<\/strong> aprob\u00f3 <strong>nuevos cuadros tarifarios para las prestadoras <\/strong>que comenzar\u00e1n a regir desde el <strong>1\u00b0 de junio de 2026<\/strong>, en el marco de la actualizaci\u00f3n mensual de tarifas y de la revisi\u00f3n quinquenal del servicio.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>La empresa Camuzzi, que brinda servicio en gran parte de la provincia de Buenos Aires, es una de las alcanzadas en la suba. Se dispuso en 5% en el cargo fijo y de casi 2 puntos en el cargo variable (que depende del consumo). El aumento se da en medio del debate sobre el futuro de la zona fr\u00eda.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>La medida fue oficializada mediante una resoluci\u00f3n publicada este viernes y forma parte del <strong>esquema de recomposici\u00f3n tarifaria impulsado por el Gobierno nacional<\/strong> tras la declaraci\u00f3n de emergencia energ\u00e9tica. Seg\u00fan el texto oficial, el incremento contempla tres componentes: la actualizaci\u00f3n del precio del gas definida por la Secretar\u00eda de Energ\u00eda, un nuevo escal\u00f3n de la Revisi\u00f3n Quinquenal Tarifaria (RQT) y el mecanismo de ajuste mensual previsto en las reglas de la licencia.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fuente:<em> Agencia DIB<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de junio habr\u00e1 suba de electricidad en dos tramos, de acuerdo al consumo y la inclusi\u00f3n de subsidios.<\/p>\n","protected":false},"author":4,"featured_media":181012,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-204725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2025\/09\/DIB-luz-y-gas.jpg?fit=800%2C450&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/204725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=204725"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/204725\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/181012"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=204725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=204725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=204725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}