{"id":202904,"date":"2026-05-11T13:02:40","date_gmt":"2026-05-11T16:02:40","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=202904"},"modified":"2026-05-11T15:31:05","modified_gmt":"2026-05-11T18:31:05","slug":"la-universidad-no-se-apaga-nueva-movilizacion-universitaria-en-olavarria","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2026\/05\/11\/la-universidad-no-se-apaga-nueva-movilizacion-universitaria-en-olavarria\/","title":{"rendered":"\u201cLa universidad no se apaga\u201d: nueva movilizaci\u00f3n universitaria en Olavarr\u00eda"},"content":{"rendered":"\n<p>Ser\u00e1 este martes desde el Centro Cultural Universitario. La decana de Ingenier\u00eda, Mar\u00eda Peralta, advirti\u00f3 sobre la p\u00e9rdida de recursos humanos y el incumplimiento de la ley de financiamiento.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Universidades p\u00fablicas de todo el pa\u00eds volver\u00e1n a movilizarse este martes en una nueva <strong>Marcha Federal Universitaria <\/strong>en defensa del presupuesto educativo y del financiamiento del sistema p\u00fablico de educaci\u00f3n superior.<strong> En Olavarr\u00eda tambi\u00e9n habr\u00e1 una convocatoria impulsada por la comunidad universitaria local.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La <strong>decana de la Facultad de Ingenier\u00eda, Mar\u00eda Peralta<\/strong>, se refiri\u00f3 a la situaci\u00f3n durante una entrevista con el programa radial <strong>Levantate, de Radio Sapiens, <\/strong>donde sostuvo que \u201clos pasos org\u00e1nicos de ir al gobierno primero, intentar di\u00e1logo, ir al Congreso, ir a la justicia, no alcanzaron\u201d.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2025\/03\/inauguracion-edificio-agrimensura-FIO-unicen-11-maria-peralta.jpg?resize=800%2C445&#038;ssl=1\" alt=\"\" class=\"wp-image-167692\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2025\/03\/inauguracion-edificio-agrimensura-FIO-unicen-11-maria-peralta.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2025\/03\/inauguracion-edificio-agrimensura-FIO-unicen-11-maria-peralta.jpg?resize=300%2C167&amp;ssl=1 300w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2025\/03\/inauguracion-edificio-agrimensura-FIO-unicen-11-maria-peralta.jpg?resize=768%2C427&amp;ssl=1 768w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2025\/03\/inauguracion-edificio-agrimensura-FIO-unicen-11-maria-peralta.jpg?resize=800%2C445&amp;ssl=1 800w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>La concentraci\u00f3n est\u00e1 prevista para las 16.30 en el Centro Cultural Universitario y la marcha comenzar\u00e1 a las 17. <\/strong>El recorrido incluir\u00e1 calles San Mart\u00edn, Riobamba, Coronel Su\u00e1rez, Vicente L\u00f3pez, Necochea y Rivadavia hasta llegar al Paseo Jes\u00fas Mend\u00eda, frente al Palacio Municipal, donde se leer\u00e1n documentos vinculados al reclamo universitario.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Peralta remarc\u00f3 que <strong>el conflicto excede al \u00e1mbito acad\u00e9mico<\/strong> y sostuvo que \u201cno es un problema de la universidad, porque en la universidad estamos todos, est\u00e1 la sociedad, est\u00e1 la familia, est\u00e1 el joven\u201d. En ese sentido, afirm\u00f3 que \u201ces un problema de la sociedad\u201d y vincul\u00f3 la protesta con la defensa de la educaci\u00f3n p\u00fablica y del cumplimiento de la ley de financiamiento universitario.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La decana tambi\u00e9n se\u00f1al\u00f3 que la universidad p\u00fablica argentina es resultado de \u201ca\u00f1os de trabajo y de lucha junto al pueblo\u201d y record\u00f3 hitos hist\u00f3ricos como la Reforma Universitaria de 1918 y la gratuidad universitaria establecida en 1949. <strong>\u201cHonremos la historia por favor\u201d<\/strong>, expres\u00f3.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>En relaci\u00f3n con la situaci\u00f3n actual del sistema universitario, Peralta advirti\u00f3 sobre la p\u00e9rdida de docentes y profesionales formados debido a los bajos salarios. \u201cEstamos perdiendo recursos humanos\u201d, asegur\u00f3, y explic\u00f3 que muchos docentes buscan alternativas laborales mejor remuneradas fuera del \u00e1mbito universitario.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>Asimismo, indic\u00f3 que <strong>alrededor del 60 por ciento de docentes y no docentes se encuentra por debajo de la l\u00ednea de pobreza <\/strong>y sostuvo que existen dificultades para cubrir vacantes y sostener concursos docentes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>\u201cLa universidad no se apaga\u201d,<\/strong> enfatiz\u00f3 finalmente la decana, al remarcar que la comunidad educativa contin\u00faa sosteniendo las actividades acad\u00e9micas mientras mantiene el reclamo por mayor financiamiento.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-central-de-noticias-olavarr-a wp-block-embed-central-de-noticias-olavarr-a\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"g5h99aMEjJ\"><a href=\"https:\/\/cdnoticias.com\/index.php\/2026\/05\/06\/el-proximo-martes-cuarta-marcha-federal-universitaria-en-olavarria\/\">El pr\u00f3ximo martes, Cuarta Marcha Federal Universitaria en Olavarr\u00eda\u00a0<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;El pr\u00f3ximo martes, Cuarta Marcha Federal Universitaria en Olavarr\u00eda\u00a0&#8221; &#8212; Central de Noticias | Olavarr\u00eda\" src=\"https:\/\/cdnoticias.com\/index.php\/2026\/05\/06\/el-proximo-martes-cuarta-marcha-federal-universitaria-en-olavarria\/embed\/#?secret=nnfh1byw4I#?secret=g5h99aMEjJ\" data-secret=\"g5h99aMEjJ\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 este martes desde el Centro Cultural Universitario. La decana de Ingenier\u00eda, Mar\u00eda Peralta, advirti\u00f3 sobre la p\u00e9rdida de recursos<\/p>\n","protected":false},"author":5,"featured_media":182714,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,1],"tags":[],"class_list":["post-202904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2025\/09\/Marcha-Universidad-Publica-Olavarria-54.jpg?fit=1024%2C680&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/202904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=202904"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/202904\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/182714"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=202904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=202904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=202904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}