{"id":202802,"date":"2026-05-09T08:32:33","date_gmt":"2026-05-09T11:32:33","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=202802"},"modified":"2026-05-09T10:43:24","modified_gmt":"2026-05-09T13:43:24","slug":"seis-detenidos-por-un-millonario-robo-de-cables-en-olavarria-y-azul","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2026\/05\/09\/seis-detenidos-por-un-millonario-robo-de-cables-en-olavarria-y-azul\/","title":{"rendered":"Seis detenidos por un millonario robo de cables en Olavarr\u00eda y Azul"},"content":{"rendered":"\n<p>La investigaci\u00f3n de la Polic\u00eda Federal sostiene que la organizaci\u00f3n oper\u00f3 entre septiembre y noviembre de 2025 y dej\u00f3 a m\u00e1s de mil usuarios sin servicio. Usaban camiones modificados y una empresa como fachada.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Una investigaci\u00f3n de la Polic\u00eda Federal Argentina desarticul\u00f3 una <strong>organizaci\u00f3n acusada de cometer millonarios robos de cableado telef\u00f3nico y de telecomunicaciones en Olavarr\u00eda y Azul, <\/strong>maniobras que habr\u00edan afectado a m\u00e1s de mil usuarios de la regi\u00f3n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La causa es encabezada por la <strong>Dra. Mar\u00eda Jos\u00e9 Buglione y el Dr. Lucas Moyano<\/strong>, quienes sostienen que la banda oper\u00f3 <strong>entre septiembre y noviembre de 2025<\/strong> mediante un esquema planificado para sustraer y trasladar grandes extensiones de cable de cobre.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>De acuerdo con la pesquisa, <strong>los acusados utilizaban como fachada la empresa \u00c1ridos A&amp;A S.R.L. para ocultar el material robado entre cargas legales. <\/strong>Adem\u00e1s, empleaban <strong>camiones y utilitarios modificados <\/strong>con malacates y compartimientos ocultos que les permit\u00edan extraer y transportar el cableado sin ser detectados.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La investigaci\u00f3n tambi\u00e9n determin\u00f3 que <strong>algunos integrantes descend\u00edan a t\u00faneles y c\u00e1maras subterr\u00e1neas pertenecientes a Telef\u00f3nica, donde realizaban cortes t\u00e9cnicos <\/strong>sobre cables de gran di\u00e1metro para concretar los robos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La Justicia imput\u00f3 provisoriamente a los acusados por<strong> asociaci\u00f3n il\u00edcita, robo triplemente calificado e interrupci\u00f3n de las comunicaciones.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>El caso genera fuerte repercusi\u00f3n por el impacto social y econ\u00f3mico de este tipo de delitos, ya que afectan servicios esenciales y perjudican tanto a vecinos como a instituciones y organismos p\u00fablicos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Fuente: Noticias de Azul.<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La investigaci\u00f3n de la Polic\u00eda Federal sostiene que la organizaci\u00f3n oper\u00f3 entre septiembre y noviembre de 2025 y dej\u00f3 a<\/p>\n","protected":false},"author":5,"featured_media":202803,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[14,1],"tags":[],"class_list":["post-202802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2026\/05\/detenidos-robo-cables.png?fit=869%2C488&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/202802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=202802"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/202802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/202803"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=202802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=202802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=202802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}