{"id":202476,"date":"2026-05-06T09:22:38","date_gmt":"2026-05-06T12:22:38","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=202476"},"modified":"2026-05-06T14:17:06","modified_gmt":"2026-05-06T17:17:06","slug":"elevan-a-naranja-el-alerta-por-tormentas-para-olavarria-y-advierten-por-fuertes-vientos-hasta-el-viernes","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2026\/05\/06\/elevan-a-naranja-el-alerta-por-tormentas-para-olavarria-y-advierten-por-fuertes-vientos-hasta-el-viernes\/","title":{"rendered":"Elevan a naranja el alerta por tormentas para Olavarr\u00eda y advierten por fuertes vientos hasta el viernes"},"content":{"rendered":"\n<p>El Servicio Meteorol\u00f3gico Nacional anticip\u00f3 tormentas fuertes para este mi\u00e9rcoles, con posible ca\u00edda de granizo y r\u00e1fagas de hasta 90 km\/h. Tambi\u00e9n rigen alertas por viento para jueves y viernes.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>El Servicio Meteorol\u00f3gico Nacional (SMN)<strong> elev\u00f3 de amarillo a naranja el alerta por tormentas <\/strong>para Olavarr\u00eda durante la<strong> tarde y la noche de este mi\u00e9rcoles.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Seg\u00fan el organismo, el \u00e1rea ser\u00e1 afectada por<strong> tormentas fuertes, algunas localmente severas, <\/strong>acompa\u00f1adas por abundantes precipitaciones en cortos per\u00edodos, intensa actividad el\u00e9ctrica, posible ca\u00edda de granizo y r\u00e1fagas que podr\u00edan superar los 90 kil\u00f3metros por hora.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Adem\u00e1s,<strong> se estiman valores de precipitaci\u00f3n acumulada de entre 60 y 90 mil\u00edmetros<\/strong>, aunque podr\u00edan registrarse montos superiores de manera localizada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"embed-twitter\"><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\ud83d\udfe0 | Alerta naranja por tormentas<br><br>\u26c8\ufe0f El Servicio Meteorol\u00f3gico Nacional emiti\u00f3 un alerta por tormentas de variada intensidad para la tarde y noche de este mi\u00e9rcoles 6.<br><br>Estar\u00e1n acompa\u00f1adas por abundantes lluvias en cortos per\u00edodos, actividad el\u00e9ctrica frecuente, posible granizo\u2026 <a href=\"https:\/\/t.co\/yOnRam66g6\">pic.twitter.com\/yOnRam66g6<\/a><\/p>&mdash; Gobierno PBA (@BAProvincia) <a href=\"https:\/\/twitter.com\/BAProvincia\/status\/2052011272573444552?ref_src=twsrc%5Etfw\">May 6, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>A este panorama se suma un <strong>alerta amarillo por vientos para el jueves<\/strong>, que comenzar\u00e1 durante la tarde y se extender\u00e1 hasta la madrugada del viernes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>De acuerdo con el SMN, el \u00e1rea ser\u00e1 afectada por v<strong>ientos del sector sur y sudoeste con velocidades de entre 35 y 50 kil\u00f3metros por hora y r\u00e1fagas que podr\u00edan alcanzar los 80 kil\u00f3metros por hora.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Las condiciones inestables continuar\u00e1n el viernes, ya que para la tarde y la noche volver\u00e1 a regir un alerta amarillo por vientos en la regi\u00f3n.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"646\" height=\"274\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2026\/05\/image.png?resize=646%2C274&#038;ssl=1\" alt=\"\" class=\"wp-image-202478\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2026\/05\/image.png?w=646&amp;ssl=1 646w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2026\/05\/image.png?resize=300%2C127&amp;ssl=1 300w\" sizes=\"auto, (max-width: 646px) 100vw, 646px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Servicio Meteorol\u00f3gico Nacional anticip\u00f3 tormentas fuertes para este mi\u00e9rcoles, con posible ca\u00edda de granizo y r\u00e1fagas de hasta 90<\/p>\n","protected":false},"author":5,"featured_media":197652,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-202476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2026\/03\/lluvia-tormenta-01.png?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/202476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=202476"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/202476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/197652"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=202476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=202476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=202476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}