{"id":202415,"date":"2026-05-05T18:50:05","date_gmt":"2026-05-05T21:50:05","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=202415"},"modified":"2026-05-05T18:50:06","modified_gmt":"2026-05-05T21:50:06","slug":"trabajos-hidraulicos-sobre-avenida-ituzaingo-norte","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2026\/05\/05\/trabajos-hidraulicos-sobre-avenida-ituzaingo-norte\/","title":{"rendered":"Trabajos hidr\u00e1ulicos sobre avenida Ituzaing\u00f3 Norte"},"content":{"rendered":"\n<p>Se trata de uno de los sectores que se vio afectado por las abundantes precipitaciones registradas recientemente.&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p>En la jornada de este martes el Municipio continu\u00f3 con el despliegue de<strong> trabajos en materia de hidr\u00e1ulica en la zona lindera a la prolongaci\u00f3n norte de la avenida Ituzaing\u00f3<\/strong>, uno de los sectores que <strong>se vio afectado por las abundantes precipitaciones registradas recientemente.\u00a0<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Se trata del sector que se encuentra<strong> luego del cruce con la Ruta Nacional N\u00b0 226<\/strong> y que da <strong>acceso a distintos establecimientos y domicilios, como as\u00ed tambi\u00e9n al relleno sanitario local.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Los trabajos cuentan con la coordinaci\u00f3n de la Secretar\u00eda de Obras, Infraestructura y Servicios P\u00fablicos. De acuerdo con lo que se detall\u00f3, en las \u00faltimas horas se realiz\u00f3 <strong>la limpieza y rectificaci\u00f3n de un canal aliviador.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Vale destacar que se trata del mismo sector donde d\u00edas atr\u00e1s se llev\u00f3 a cabo tambi\u00e9n la colocaci\u00f3n de alcantarillas en distintos tramos, con el objetivo de permitir el normal escurrimiento de aguas, pero tambi\u00e9n permitir la transitabilidad por el sector.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>Los trabajos se enmarcan no s\u00f3lo en el estudio y seguimiento que se realiza desde la mencionada \u00e1rea, sino tambi\u00e9n en respuesta a las inquietudes y pedidos de vecinos y vecinas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Por \u00faltimo<strong>, este martes,<\/strong> de manera paralela,<strong> se realizaron trabajos de mantenimiento vial en los barrios AOMA, Villa Aurora y en el sector lindero a las avenidas Col\u00f3n y Eva Per\u00f3n<\/strong> (Ex Circunvalaci\u00f3n).<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de uno de los sectores que se vio afectado por las abundantes precipitaciones registradas recientemente.&nbsp; En la jornada<\/p>\n","protected":false},"author":6,"featured_media":202417,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-202415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2026\/05\/ituzaingonorte-trabajos2.jpg?fit=900%2C415&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/202415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=202415"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/202415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/202417"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=202415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=202415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=202415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}