{"id":202369,"date":"2026-05-04T20:43:55","date_gmt":"2026-05-04T23:43:55","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=202369"},"modified":"2026-05-04T20:43:57","modified_gmt":"2026-05-04T23:43:57","slug":"el-gobierno-dispuso-un-refuerzo-de-subsidios-al-gas-y-elevara-la-bonificacion-al-75-en-mayo","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2026\/05\/04\/el-gobierno-dispuso-un-refuerzo-de-subsidios-al-gas-y-elevara-la-bonificacion-al-75-en-mayo\/","title":{"rendered":"El Gobierno dispuso un refuerzo de subsidios al gas y elevar\u00e1 la bonificaci\u00f3n al 75% en mayo"},"content":{"rendered":"\n<p>La medida alcanza a casi 4,8 millones de usuarios y busca amortiguar el impacto de la suba internacional de la energ\u00eda en las facturas.<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p>El Gobierno nacional resolvi\u00f3 otorgar una<strong> bonificaci\u00f3n extraordinaria del 25% sobre las tarifas de gas durante mayo, lo que elevar\u00e1 al 75% el nivel de subsidio sobre el bloque de consumo alcanzado por el esquema oficial para los usuarios de menores ingresos.<\/strong><\/p>\n\n\n\n<p>La decisi\u00f3n fue formalizada a trav\u00e9s de la Resoluci\u00f3n 11\/2026 de la Secretar\u00eda de Energ\u00eda, publicada en el Bolet\u00edn Oficial, y<strong> alcanzar\u00e1 a 4.780.000 usuarios en todo el pa\u00eds. La medida se enmarca en el r\u00e9gimen de Subsidios Energ\u00e9ticos Focalizados (SEF), implementado a fines de 2025.<\/strong><\/p>\n\n\n\n<p>De acuerdo a lo establecido, <strong>quienes ya reciben asistencia estatal contar\u00e1n durante mayo con un 25% adicional de bonificaci\u00f3n, que se suma al 50% de subsidio base vigente. En los meses previos, ese porcentaje adicional hab\u00eda sido reducido progresivamente \u2014por ejemplo, en abril fue del 18%\u2014, pero ahora se restituye de manera excepcional.<\/strong><\/p>\n\n\n\n<p>Desde <strong>el Ejecutivo se\u00f1alaron que la decisi\u00f3n responde al contexto internacional<\/strong>, marcado por tensiones geopol\u00edticas que impactan en los precios del gas. En ese sentido, explicaron que, si bien Argentina cuenta con producci\u00f3n propia, mantiene una integraci\u00f3n con el mercado global a trav\u00e9s de importaciones de Gas Natural Licuado (GNL), lo que provoca que las variaciones externas incidan en el costo local.<\/p>\n\n\n\n<p>En los considerandos de la norma se remarca que <em>\u201clas variaciones en los precios internacionales impactan de manera directa en el costo de abastecimiento del gas natural en el Punto de Ingreso al Sistema de Transporte (PIST)\u201d<\/em>, justificando as\u00ed el refuerzo temporal de la asistencia estatal.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>La bonificaci\u00f3n adicional ser\u00e1 aplicada \u00fanicamente durante mayo de 2026 y alcanzar\u00e1 tanto a usuarios residenciales como a entidades sin fines de lucro, entre ellas clubes de barrio y organizaciones sociales incluidas en el r\u00e9gimen.<\/p>\n<\/blockquote>\n\n\n\n<p>En paralelo, <strong>el Gobierno mantuvo sin modificaciones la pol\u00edtica de reducci\u00f3n gradual de subsidios en el servicio el\u00e9ctrico. Seg\u00fan se inform\u00f3, en ese segmento continuar\u00e1 la baja progresiva de la bonificaci\u00f3n extraordinaria, que comenz\u00f3 en 25% en enero y se reducir\u00e1 hasta llegar a 0% en diciembre.<\/strong><\/p>\n\n\n\n<p>Desde Naci\u00f3n destacaron que<strong> el objetivo es avanzar hacia un esquema de subsidios \u201cm\u00e1s simple, transparente y sostenible\u201d,<\/strong> focalizado en los sectores que m\u00e1s lo necesitan y con mayor previsibilidad en el impacto de las tarifas.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La medida alcanza a casi 4,8 millones de usuarios y busca amortiguar el impacto de la suba internacional de la<\/p>\n","protected":false},"author":2,"featured_media":9224,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,1],"tags":[],"class_list":["post-202369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2020\/12\/gas-natural.jpg?fit=854%2C465&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/202369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=202369"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/202369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/9224"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=202369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=202369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=202369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}