{"id":202331,"date":"2026-05-04T16:30:06","date_gmt":"2026-05-04T19:30:06","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=202331"},"modified":"2026-05-04T16:31:55","modified_gmt":"2026-05-04T19:31:55","slug":"este-martes-jornada-comunitaria-sobre-cuidados-integrales","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2026\/05\/04\/este-martes-jornada-comunitaria-sobre-cuidados-integrales\/","title":{"rendered":"Este martes, Jornada Comunitaria sobre Cuidados Integrales"},"content":{"rendered":"\n<p>Ser\u00e1 desde las 10 horas en los barrios Nicol\u00e1s Avellaneda y el sector de avenida Pringles Sur.<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p>Este <strong>martes 5 de mayo, a partir de las 10 horas,<\/strong> se llevar\u00e1 a cabo una <strong>Jornada Comunitaria sobre Cuidados Integrales, <\/strong>organizada por la Mesa de Gesti\u00f3n Territorial N\u00ba 7 (zona Avellaneda), que comprender\u00e1 a los<strong> barrios Nicol\u00e1s Avellaneda y el sector de avenida Pringles Sur.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En la jornada<strong> se establecer\u00e1 una posta que ser\u00e1 la base de la actividad, ubicada en Calle 10 y Saavedra (plaza), <\/strong>donde estar\u00e1 <strong>personal de enfermer\u00eda completando esquemas de vacunaci\u00f3n, y tambi\u00e9n el equipo del Programa Municipal Salud Sexual y Reproductiva<\/strong>, as\u00ed como tambi\u00e9n equipo de la <strong>Direcci\u00f3n de Mujeres, G\u00e9neros y Diversidad <\/strong>quienes adem\u00e1s brindar\u00e1n <strong>informaci\u00f3n, asesoramiento y entrega de m\u00e9todos anticonceptivos.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Como parte de la propuesta, en paralelo se desplegar\u00e1 un operativo puerta a puerta donde se indagar\u00e1 sobre vacunaci\u00f3n de los residentes del hogar visitado, invit\u00e1ndolos a pasar por la posta. En este sentido se har\u00e1 especial hincapi\u00e9 en la importancia de tener al d\u00eda el calendario de vacunaci\u00f3n.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>Por otra parte se brindar\u00e1 informaci\u00f3n sobre <strong>el programa de separaci\u00f3n de residuos, con la participaci\u00f3n de promotoras ambientales del Programa GIRO<\/strong> (Gesti\u00f3n Integral de Residuos de Olavarr\u00eda).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La actividad contar\u00e1 con la participaci\u00f3n de equipos de instituciones educativas del territorio, promotores de salud, personal de enfermer\u00eda de los CAPS N\u00ba 8 y 17, estudiantes de la Facultad de Medicina, promotoras ambientales, personal municipal de la Direcci\u00f3n de Mujeres, G\u00e9neros y Diversidad, Direcci\u00f3n de Integraci\u00f3n Comunitaria y Personas Mayores, y del Programa Municipal Salud Sexual y Reproductiva.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 desde las 10 horas en los barrios Nicol\u00e1s Avellaneda y el sector de avenida Pringles Sur. Este martes 5<\/p>\n","protected":false},"author":6,"featured_media":63327,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-202331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/08\/DIB-vacunacion-ninos.jpg?fit=1024%2C682&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/202331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=202331"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/202331\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/63327"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=202331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=202331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=202331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}