{"id":194013,"date":"2026-01-31T18:55:29","date_gmt":"2026-01-31T21:55:29","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=194013"},"modified":"2026-02-03T09:48:34","modified_gmt":"2026-02-03T12:48:34","slug":"transporte-publico-de-pasajeros-el-municipio-inicio-actuaciones-por-diversas-infracciones","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2026\/01\/31\/transporte-publico-de-pasajeros-el-municipio-inicio-actuaciones-por-diversas-infracciones\/","title":{"rendered":"Transporte P\u00fablico de Pasajeros: el Municipio inici\u00f3 actuaciones por diversas infracciones"},"content":{"rendered":"\n<p>Las tareas son realizadas desde la Secretar\u00eda de Protecci\u00f3n Ciudadana, a trav\u00e9s de la Coordinaci\u00f3n de Transporte.&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p>El Municipio de Olavarr\u00eda lleva a cabo de manera permanente <strong>trabajos preventivos y de control del servicio de transporte p\u00fablico de pasajeros<\/strong>, una medida que abarca el <strong>funcionamiento de colectivos, taxis y remises de nuestra ciudad<\/strong> para constatar el cumplimiento no s\u00f3lo de las normativas vigentes, sino tambi\u00e9n contratos y condiciones que requieren sus usuarios y usuarias.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Las tareas son realizadas desde la Secretar\u00eda de Protecci\u00f3n Ciudadana, a trav\u00e9s de la Coordinaci\u00f3n de Transporte, mediante <strong>controles que se llevan a cabo en diferentes d\u00edas y horarios, pero con especial \u00e9nfasis en las denominadas \u201choras pico\u201d,<\/strong> para verificar el correcto cumplimiento en las frecuencias del transporte p\u00fablico de pasajeros, en las distintas l\u00edneas del servicio urbano.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>En ese marco, se logr\u00f3 llevar a cabo tres constataciones sobre diferentes l\u00edneas por incumplimiento de las frecuencias de recorrido, conforme con lo establecido en las Ordenanzas Municipales 4356\/18 y 4367\/19.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>De manera paralela, tambi\u00e9n <strong>se detect\u00f3 la actividad de veh\u00edculos particulares que eran utilizados como remises, sin contar con la habilitaci\u00f3n correspondiente, <\/strong>lo que se traduce adem\u00e1s en una<strong> infracci\u00f3n a la Ley Nacional de Tr\u00e1nsito, la N\u00b0 24.449.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Vale destacar, por \u00faltimo, que tambi\u00e9n<strong> se control\u00f3 la correcta utilizaci\u00f3n de las paradas exclusivas para taxis. <\/strong>Las actas labradas fueron puestas a disposici\u00f3n tanto del Juzgado de Faltas Municipal como de la Subsecretar\u00eda de Asuntos Legales, para que sigan sus respectivos cursos administrativos.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las tareas son realizadas desde la Secretar\u00eda de Protecci\u00f3n Ciudadana, a trav\u00e9s de la Coordinaci\u00f3n de Transporte.&nbsp; El Municipio de<\/p>\n","protected":false},"author":6,"featured_media":194015,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-194013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2026\/01\/controles-proteccion-ciudadana1.jpg?fit=900%2C457&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/194013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=194013"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/194013\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/194015"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=194013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=194013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=194013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}