{"id":191865,"date":"2026-01-01T11:41:53","date_gmt":"2026-01-01T14:41:53","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=191865"},"modified":"2026-01-01T11:41:55","modified_gmt":"2026-01-01T14:41:55","slug":"se-mantiene-el-alerta-por-viento-para-este-jueves","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2026\/01\/01\/se-mantiene-el-alerta-por-viento-para-este-jueves\/","title":{"rendered":"Se mantiene el alerta por viento para este jueves"},"content":{"rendered":"<p>El Servicio Meteorol\u00f3gico Nacional emiti\u00f3 la advertencia para Olavarr\u00eda y gran parte de la provincia de Buenos Aires. Para los pr\u00f3ximos d\u00edas se espera que se mantenga el descenso de las temperaturas.<!--more--><\/p>\n<hr \/>\n<p>El <strong>Servicio Meteorol\u00f3gico Nacional (SMN)<\/strong> emiti\u00f3 un <strong>alerta por viento para Olavarr\u00eda<\/strong> durante la<strong> noche de este jueves.<\/strong><\/p>\n<p>Tal como se inform\u00f3, la advertencia es de<strong> nivel amarillo<\/strong> alcanza a las <strong>regiones centro, sur y oeste de la provincia de Buenos Aires<\/strong>. Tambi\u00e9n a La Pampa, R\u00edo Negro, Neuqu\u00e9n y San Luis.<\/p>\n<blockquote><p>El organismo nacional inform\u00f3 para Olavarr\u00eda, Laprida y La Madrid que \u201cel \u00e1rea ser\u00e1 afectada por vientos del sector sur con velocidades de entre 40 y 55 km\/h y r\u00e1fagas que podr\u00edan alcanzar los 75 km\/h\u201d.<\/p><\/blockquote>\n<p>Para este jueves se pronostic\u00f3 una<strong> m\u00e1xima de 31\u00ba<\/strong> y la <strong>m\u00ednima de la jornada fue de 11,3\u00ba<\/strong> que se registr\u00f3 a las 4.30. Para los pr\u00f3ximos d\u00edas se espera que se mantenga el descenso de las temperaturas: <strong>el viernes la m\u00e1xima ser\u00e1 de 26\u00ba y el s\u00e1bado, de 25\u00ba.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Servicio Meteorol\u00f3gico Nacional emiti\u00f3 la advertencia para Olavarr\u00eda y gran parte de la provincia de Buenos Aires. Para los<\/p>\n","protected":false},"author":4,"featured_media":191867,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-191865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2026\/01\/alerta-meteorologica-por-viento-1-de-enero-2026.jpg?fit=1000%2C557&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/191865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=191865"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/191865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/191867"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=191865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=191865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=191865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}