{"id":190354,"date":"2025-12-12T21:36:00","date_gmt":"2025-12-13T00:36:00","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=190354"},"modified":"2025-12-13T10:31:50","modified_gmt":"2025-12-13T13:31:50","slug":"confirmaron-un-caso-positivo-de-hantavirus-en-olavarria","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2025\/12\/12\/confirmaron-un-caso-positivo-de-hantavirus-en-olavarria\/","title":{"rendered":"Confirmaron un caso positivo de hantavirus en Olavarr\u00eda"},"content":{"rendered":"\n<p>Se trata de un paciente de 16 a\u00f1os que permanece internado en el Hospital Municipal con evoluci\u00f3n favorable y seguimiento permanente.<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p>El Municipio inform\u00f3 que <strong>en el transcurso de las \u00faltimas horas se confirm\u00f3 un caso positivo de hantavirus en el Partido. Se trata de un paciente de 16 a\u00f1os, quien permanece internado en el Hospital Municipal \u201cDr. H\u00e9ctor Cura\u201d, con evoluci\u00f3n favorable y bajo seguimiento permanente.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Desde el primer momento intervinieron equipos de salud del Municipio, la Direcci\u00f3n de Epidemiolog\u00eda e Inmunizaciones y la Direcci\u00f3n de Bromatolog\u00eda, a partir de la aparici\u00f3n de s\u00edntomas compatibles con la enfermedad. El diagn\u00f3stico fue confirmado mediante los estudios de laboratorio correspondientes.<\/p>\n<\/blockquote>\n\n\n\n<p>El hantavirus suele manifestarse con <strong>fiebre, dolores musculares, escalofr\u00edos, cefaleas, n\u00e1useas, v\u00f3mitos, dolor abdominal y diarrea. Ante la presencia de este tipo de s\u00edntomas, se solicita a la poblaci\u00f3n que se acerque al centro de salud m\u00e1s cercano.<\/strong><\/p>\n\n\n\n<p>El hantavirus es un <strong>grupo de virus que infectan a determinados roedores y el contagio en humanos se produce principalmente por la inhalaci\u00f3n de part\u00edculas virales presentes en la orina, heces o saliva de estos animales.<\/strong> Tambi\u00e9n puede transmitirse por contacto directo con roedores o sus secreciones, mordeduras o contaminaci\u00f3n de alimentos.<\/p>\n\n\n\n<p>Los s\u00edntomas suelen aparecer <strong>entre una y seis semanas despu\u00e9s del contagio e incluyen fiebre, dolor muscular intenso, dolor de cabeza, n\u00e1useas, v\u00f3mitos, dolor abdominal, malestar general, tos y dificultad respiratoria. El s\u00edndrome pulmonar por hantavirus puede ser potencialmente mortal, por lo que requiere atenci\u00f3n m\u00e9dica urgente.<\/strong><\/p>\n\n\n\n<p>Desde el Municipio se record\u00f3 la importancia de <strong>adoptar medidas de prevenci\u00f3n, tanto en el hogar como en zonas rurales, manteniendo viviendas y galpones libres de roedores, tapando grietas, guardando alimentos en recipientes herm\u00e9ticos y evitando barrer en seco excrementos, que deben limpiarse con soluci\u00f3n de lavandina. Tambi\u00e9n se recomienda ventilar durante al menos 30 minutos los espacios cerrados antes de limpiarlos.<\/strong><\/p>\n\n\n\n<p>En actividades al aire libre,<strong> se aconseja no dormir directamente sobre el suelo, evitar el contacto con roedores vivos o muertos, consumir agua potable, proteger los alimentos y mantener limpios los espacios de campamento.<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de un paciente de 16 a\u00f1os que permanece internado en el Hospital Municipal con evoluci\u00f3n favorable y seguimiento<\/p>\n","protected":false},"author":2,"featured_media":165389,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-190354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2025\/02\/hospital-frente-06.jpg?fit=1000%2C556&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/190354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=190354"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/190354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/165389"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=190354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=190354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=190354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}