{"id":149515,"date":"2022-06-23T17:52:12","date_gmt":"2022-06-23T20:52:12","guid":{"rendered":"http:\/\/centraldeportes.com.ar\/?p=18330"},"modified":"2022-06-23T17:52:12","modified_gmt":"2022-06-23T20:52:12","slug":"hockey-un-fin-de-semana-con-muchos-partidos-y-dos-podios","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2022\/06\/23\/hockey-un-fin-de-semana-con-muchos-partidos-y-dos-podios\/","title":{"rendered":"Hockey: un fin de semana con muchos partidos y dos podios"},"content":{"rendered":"<p>Hubo mucha actividad para el hockey de Estudiantes que complet\u00f3 la actividad en varones, jug\u00f3 otra fecha en Damas, particip\u00f3 de un encuentro y adem\u00e1s el equipo Sub14 de Federaci\u00f3n tendr\u00e1 presencia local.<!--more--><\/p>\n<hr \/>\n<p>Primero, el viernes en Tandil, Estudiantes fue subcampe\u00f3n en la categor\u00eda Sub15. \u00a0Primero gan\u00f3 la Semifinal ante Independiente por 4 a 1 y cay\u00f3 ante UNCAS en la definici\u00f3n por 3 a 0 para ser el segundo mejor equipo del Torneo Apertura.<\/p>\n<p>&nbsp;<\/p>\n<p>Otro de los planteles masculinos que termin\u00f3 el primer torneo del a\u00f1o fue el de Primera Divisi\u00f3n que recibi\u00f3 a Lil\u00e1n de Laprida en el partido por el tercer puesto y fue goleada por 11 a 0. Los goles \u201calbinegros\u201d los hicieron Nicol\u00e1s Cerra (2), Claudio Alcaza (4), Germ\u00e1n Ben\u00edtez (2) y Ger\u00f3nimo Mart\u00ednez Amoroso (3).<\/p>\n<p>&nbsp;<\/p>\n<p>[soliloquy slug=&#8221;hockey-12&#8243;]<\/p>\n<p>&nbsp;<\/p>\n<p>En la rama femenina, Estudiantes recibi\u00f3 a Los 50 de Tandil en la tarde del s\u00e1bado y los resultados fueron:<\/p>\n<p>&nbsp;<\/p>\n<p>Sub 14: CAE 7 (Victoria Meira -7-)\u2013 2 Los 50<\/p>\n<p>Sub 16: CAE 0 \u2013 4 Los 50<\/p>\n<p>Sub 19: CAE 2 (Juana Arouxet y Justina Lohidoy) \u2013 1 Los 50<\/p>\n<p>Intermedia: CAE 0 \u2013 4 Los 50<\/p>\n<p>Primera: CAE 0 \u2013 6 Los 50<\/p>\n<p>&nbsp;<\/p>\n<p>Por otro lado, las categor\u00edas m\u00e1s peque\u00f1as de Damas y Caballeros (Sub 8 y Sub 10) participaron de un encuentro de Hockey en el Club Lil\u00e1n de Laprida.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s, este jueves inici\u00f3 en Bah\u00eda Blanca el Torneo Regional de Selecciones Sub14 y en el equipo de la Federaci\u00f3n que buscar\u00e1 la plaza al Campeonato Argentino estar\u00e1 Kim Della Maggiora.<\/p>\n<p>&nbsp;<\/p>\n<p>Se jugar\u00e1n 33 partidos repartidos en las canchas de la Asociaci\u00f3n Bahiense y el Club Pac\u00edfico y Tandil, con la albinegra Kim Della Maggiora, la selecci\u00f3n compartir\u00e1 la Zona C junto a la Federaci\u00f3n Cuenca del Salado y la Federaci\u00f3n Uruguaya.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hubo mucha actividad para el hockey de Estudiantes que complet\u00f3 la actividad en varones, jug\u00f3 otra fecha en Damas, particip\u00f3<\/p>\n","protected":false},"author":96739694,"featured_media":149516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[30,1],"tags":[],"class_list":["post-149515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-polideportivo","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/06\/hockey.jpg?fit=1280%2C847&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/149515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/96739694"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=149515"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/149515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/149516"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=149515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=149515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=149515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}