{"id":148105,"date":"2022-05-22T18:23:07","date_gmt":"2022-05-22T21:23:07","guid":{"rendered":"http:\/\/centraldeportes.com.ar\/?p=16646"},"modified":"2022-05-22T18:23:07","modified_gmt":"2022-05-22T21:23:07","slug":"paloma-routaboul-entreno-una-semana-con-la-seleccion-argentina","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2022\/05\/22\/paloma-routaboul-entreno-una-semana-con-la-seleccion-argentina\/","title":{"rendered":"Paloma Routaboul entren\u00f3 una semana con la Selecci\u00f3n Argentina"},"content":{"rendered":"<p>La jugadora de Estudiantes entren\u00f3 en el Complejo de La Pedrera de Villa Mercedes con el equipo Sub19 de la Selecci\u00f3n Argentina.<!--more--><\/p>\n<hr \/>\n<p>El seleccionado nacional de v\u00f3ley, bajo las \u00f3rdenes del entrenador Eduardo Rodr\u00edguez, se prepara para el Campeonato Sudamericano a jugarse del 5 al 13 de septiembre; el cual otorgar\u00e1 plazas para el Mundial 2023 y en una nueva semana de entrenamientos, estuvo la olavarriense Routaboul.<\/p>\n<p>&nbsp;<\/p>\n<p>Finalizada la concentraci\u00f3n, la deportista olavarriense viaj\u00f3 a Bah\u00eda Blanca para sumarse a los entrenamientos de la Selecci\u00f3n Bonaerense Sub18, que participar\u00e1 del 24 al 28 de mayo del Argentino de Selecciones en Chapadmalal.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La jugadora de Estudiantes entren\u00f3 en el Complejo de La Pedrera de Villa Mercedes con el equipo Sub19 de la<\/p>\n","protected":false},"author":96739694,"featured_media":146868,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[30,1],"tags":[],"class_list":["post-148105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-polideportivo","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/02\/routaboul.png?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/148105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/96739694"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=148105"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/148105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/146868"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=148105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=148105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=148105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}