{"id":139496,"date":"2022-10-13T16:32:11","date_gmt":"2022-10-13T19:32:11","guid":{"rendered":"http:\/\/centraldeportes.com.ar\/?p=24783"},"modified":"2025-02-10T21:43:05","modified_gmt":"2025-02-11T00:43:05","slug":"handball-terminaron-los-entrenamientos-de-la-seleccion-argentina","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2022\/10\/13\/handball-terminaron-los-entrenamientos-de-la-seleccion-argentina\/","title":{"rendered":"Handball: terminaron los entrenamientos de la Selecci\u00f3n Argentina"},"content":{"rendered":"<p>Culmin\u00f3 este jueves en horas del mediod\u00eda la concentraci\u00f3n de la Selecci\u00f3n Argentina de Handball Sub14 en el Club Estudiantes.<\/p>\n<p><!--more--><\/p>\n<hr \/>\n<p>Luego de varias pr\u00e1cticas del programa Futuro 2028 con la presencia de casi 50 deportistas y de una ronda de preguntas en una de las jornadas, el equipo de trabajo de la Selecci\u00f3n Argentina de Menores se despidi\u00f3 de Olavarr\u00eda en el transcurso del jueves.<\/p>\n<p>&nbsp;<\/p>\n<p>Hubo intensos m\u00f3dulos de trabajos en el Macrogimnasio del Parque Guerrero a cargo del equipo de trabajo coordinado por Eduardo \u201cDady\u201d Gallardo.<\/p>\n<p>&nbsp;<\/p>\n<p>Por otro lado, los equipos de Estudiantes jugaron amistosos en Tandil ante Unicen en el Branca Center.<\/p>\n<p>&nbsp;<\/p>\n<p>Los resultados:<br \/>\nMini: CAE 4 \u2013 0 UNICEN<br \/>\nInfantiles: CAE 33 \u2013 20 UNICEN<br \/>\nMayores Femenino: CAE 26 \u2013 35 UNICEN<br \/>\nMayores Masculino: CAE 41 \u2013 32 UNICEN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Culmin\u00f3 este jueves en horas del mediod\u00eda la concentraci\u00f3n de la Selecci\u00f3n Argentina de Handball Sub14 en el Club Estudiantes.<\/p>\n","protected":false},"author":96739694,"featured_media":152349,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[30,1],"tags":[],"class_list":["post-139496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-polideportivo","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2022\/10\/Photo_1665529804573.jpg?fit=1500%2C1000&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/139496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/96739694"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=139496"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/139496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/152349"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=139496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=139496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=139496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}