{"id":139210,"date":"2023-03-02T21:15:49","date_gmt":"2023-03-03T00:15:49","guid":{"rendered":"http:\/\/centraldeportes.com.ar\/?p=31190"},"modified":"2025-02-10T23:33:05","modified_gmt":"2025-02-11T02:33:05","slug":"el-hockey-de-estudiantes-tuvo-un-finde-de-accion","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2023\/03\/02\/el-hockey-de-estudiantes-tuvo-un-finde-de-accion\/","title":{"rendered":"El hockey de Estudiantes tuvo un \u201cfinde\u201d de acci\u00f3n"},"content":{"rendered":"<p>Entre s\u00e1bado y domingo, el hockey del Club Atl\u00e9tico Estudiantes comenz\u00f3 con los partidos preparatorios de cara a las competencias organizadas por la Federaci\u00f3n Tandilense de Hockey.<!--more--><\/p>\n<hr \/>\n<p>El s\u00e1bado, recibi\u00f3, en la cancha sint\u00e9tica del Parque Guerrero, a Ciudad de Bol\u00edvar y fueron todos triunfos para el \u201cBataraz\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>La jornada cont\u00f3 con gran cantidad de partidos para aprovechar la llegada del elenco de la vecina localidad.<\/p>\n<p>&nbsp;<\/p>\n\n<p>&nbsp;<\/p>\n<p>Ya en la jornada dominical, el equipo de Primera Masculina viaj\u00f3 a Coronel Su\u00e1rez para jugar un cuadrangular amistoso entre el organizador Blanco y Negro, Estudiantes, El Nacional de Bah\u00eda Blanca y Puerto Belgrano de Punta Alta.<\/p>\n<p>&nbsp;<\/p>\n<p>En lo que respecta a resultados, Estudiantes gan\u00f3 dos encuentros y perdi\u00f3 solamente uno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre s\u00e1bado y domingo, el hockey del Club Atl\u00e9tico Estudiantes comenz\u00f3 con los partidos preparatorios de cara a las competencias<\/p>\n","protected":false},"author":96739694,"featured_media":153545,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[30,1],"tags":[],"class_list":["post-139210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-polideportivo","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/03\/hockey-1.jpeg?fit=1500%2C1000&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/139210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/96739694"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=139210"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/139210\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/153545"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=139210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=139210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=139210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}