{"id":132677,"date":"2024-12-18T07:58:21","date_gmt":"2024-12-18T10:58:21","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=132677"},"modified":"2024-12-18T07:58:23","modified_gmt":"2024-12-18T10:58:23","slug":"inaugura-la-muestra-baquets-los-inicios-del-automovilismo-deportivo","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2024\/12\/18\/inaugura-la-muestra-baquets-los-inicios-del-automovilismo-deportivo\/","title":{"rendered":"Inaugura la muestra \u201cBaquets, los inicios del automovilismo deportivo\u201d"},"content":{"rendered":"\n<p>Ser\u00e1 el viernes 20 en el Museo \u201cHermanos Emiliozzi\u201d. Se trata de una exposici\u00f3n est\u00e1tica de baquets de vecinos de Olavarr\u00eda.<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p>El <strong>Museo \u201cHermanos Emiliozzi\u201d<\/strong> invita a participar de la apertura de la pr\u00f3xima muestra <strong>\u201cBaquets, los inicios del automovilismo deportivo<\/strong>\u201d que se llevar\u00e1 a cabo el d\u00eda <strong>viernes 20 de diciembre, a las 19 horas.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Se trata de una exposici\u00f3n est\u00e1tica de <strong>baquets de vecinos de Olavarr\u00eda<\/strong>, una muestra homenaje a los<strong> inicios de los gringos Emiliozzi <\/strong>en el automovilismo deportivo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Asimismo, cuenta con <strong>material fotogr\u00e1fico de Lucrecia Meschini <\/strong>y <strong>repuestos alusivos, <\/strong>para recrear una \u00e9poca de artesan\u00edas y pasi\u00f3n por los fierros\u00a0 que llega hasta nuestros d\u00edas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>La ingeniera Lucrecia Meschini, es una apasionada de la fotograf\u00eda de autos. Expone en esta ocasi\u00f3n fotos que ha tomado en salidas de amigos con baquets\u00a0 y en el\u00a0 GP Argentino de\u00a0 baquets.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>Los <strong>inicios de los Gringos Emiliozzi en el automovilismo deportivo, fueron en veh\u00edculos baquets<\/strong>. Torcuato Emiliozzi con 20 a\u00f1os debut\u00f3 como acompa\u00f1ante de Jos\u00e9 Valerga en Fuerza Limitada con un Ford A 1929.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Con esa misma baquet, debuta como piloto el 24 de Mayo de 1936 en Las Flores. Luego construy\u00f3 un Fiat 519 apodado \u201cel Ventarr\u00f3n\u201d, y termin\u00f3 corriendo con Ford T&nbsp; donde gan\u00f3 4 carreras.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Dante debut\u00f3 en el automovilismo en el a\u00f1o 1940 en la categor\u00eda Ford T Standard&nbsp; con un Ford T 1926: corri\u00f3 18 carreras, gan\u00f3 11 y&nbsp; lleg\u00f3 2\u00b0 en 4 oportunidades.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Sobre el Ford T, el historiador Walter Minor en su libro \u201cSin Galera\u201d menciona que se trata de <em>\u201cuna carrocer\u00eda muy primaria que contrastaba con un motor extraordinario que lo hizo imbatible por muchos a\u00f1os en la regi\u00f3n\u201d.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Baquets<\/strong><\/p>\n\n\n\n<p>Una baquet, as\u00ed llamada por la singularidad de sus asientos con que estos coches eran equipados,<strong> son autos concebidos para correr<\/strong>, chasis con carrocer\u00edas m\u00ednimas, que <strong>marcaron el inicio del automovilismo deportivo.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Las primeras <em>baquets<\/em> carec\u00edan de dise\u00f1o. S\u00f3lo se alivianaba\u00a0 el auto para mejorar la relaci\u00f3n peso-potencia y que entren lo mejor posible piloto y acompa\u00f1ante. Con los a\u00f1os se fue perfeccionando el dise\u00f1o, hasta llegar a las m\u00e1s lindas, estilizadas y livianas carrocer\u00edas de aluminio.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>Se recuerda que el Museo Emiliozzi (Necochea 3229) abre sus puertas los d\u00edas: <strong>martes, mi\u00e9rcoles, jueves y viernes de 8 a 14 horas; s\u00e1bados, domingos y feriados de 16 a 19 horas.<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 el viernes 20 en el Museo \u201cHermanos Emiliozzi\u201d. Se trata de una exposici\u00f3n est\u00e1tica de baquets de vecinos de<\/p>\n","protected":false},"author":6,"featured_media":85176,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,1],"tags":[],"class_list":["post-132677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/05\/Cultura-TC-50-en-Emiliozzi-4-1024x673-1.jpg?fit=1024%2C673&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/132677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=132677"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/132677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/85176"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=132677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=132677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=132677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}