{"id":13106,"date":"2021-02-06T11:49:29","date_gmt":"2021-02-06T14:49:29","guid":{"rendered":"http:\/\/www.centraldenoticias.com.ar\/?p=13106"},"modified":"2021-02-06T13:21:14","modified_gmt":"2021-02-06T16:21:14","slug":"avanzan-las-investigaciones-por-el-robo-de-39-vacunos","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2021\/02\/06\/avanzan-las-investigaciones-por-el-robo-de-39-vacunos\/","title":{"rendered":"Avanzan las investigaciones por el robo de 39 vacunos"},"content":{"rendered":"<p>Las tareas llegaron hasta la ciudad de Bol\u00edvar y consistieron en la realizaci\u00f3n de \u201crodeos\u201d en distintos establecimientos rurales para tratar de identificar los animales faltantes.<!--more--><\/p>\n<hr \/>\n<p>Un robo de importantes caracter\u00edsticas se denunci\u00f3 el pasado viernes en el Destacamento de Espigas:<a href=\"https:\/\/cdnoticias.com\/index.php\/2021\/02\/03\/llamativo-robo-en-cercanias-de-recalde-faltaron-39-vacas\/\" target=\"_blank\" rel=\"noopener\"> faltaron 39 vacunos de un campo ubicado a unos 40 kil\u00f3metros de Recalde y a unos 10 kil\u00f3metros de la ruta 60.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>El lote de animales robados est\u00e1 valuado en poco<strong> m\u00e1s de 2 millones de pesos.<\/strong> La denuncia penal fue radicada por parte de la propietaria del <strong>establecimiento rural \u201cEl Arroyito\u201d<\/strong>, ubicado en el Cuartel XVII del partido de Olavarr\u00eda, en donde se especific\u00f3 el faltante de los<strong>\u00a0vacunos de raza Aberdeen Angus negras y coloradas.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Ante esta situaci\u00f3n, <strong>se diagramaron tareas investigativas<\/strong> encabezadas por la Ayudant\u00eda Especializada de Delitos Rurales a cargo del Dr. Juan Ma\u00f1ero y del fiscal Lucas Moyano, en forma conjunta con efectivos del destacamento de Espigas, Recalde, comisar\u00eda Primera y Comando de Prevenci\u00f3n Rural.<\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-13107\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-05-at-20.45.53.jpeg?resize=768%2C1024&#038;ssl=1\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-05-at-20.45.53.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-05-at-20.45.53.jpeg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-05-at-20.45.53.jpeg?w=774&amp;ssl=1 774w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Las tareas <strong>se extendieron a localidades linderas como Recalde y llegaron hasta la ciudad de Bol\u00edvar.<\/strong>\u00a0Consistieron en<strong> \u201crodeos\u201d en distintos campos de la zona,<\/strong> con la finalidad de establecer los animales faltantes.<\/p>\n<p>&nbsp;<\/p>\n<p>Hasta el momento, no hubo resultados positivos, aunque se inform\u00f3 que <strong>se seguir\u00e1 investigando en otros establecimientos.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>En forma paralela, tambi\u00e9n se est\u00e1n realizando <strong>operativos de interceptaci\u00f3n vehicular<\/strong> (preferentemente camiones de carga), tanto en ruta como en caminos vecinales, que transporten ganado tanto mayor como menor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las tareas llegaron hasta la ciudad de Bol\u00edvar y consistieron en la realizaci\u00f3n de \u201crodeos\u201d en distintos establecimientos rurales para<\/p>\n","protected":false},"author":5,"featured_media":13108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[14,1],"tags":[],"class_list":["post-13106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-05-at-20.45.28.jpeg?fit=1032%2C774&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/13106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=13106"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/13106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/13108"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=13106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=13106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=13106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}