{"id":126785,"date":"2024-10-01T12:30:02","date_gmt":"2024-10-01T15:30:02","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=126785"},"modified":"2024-10-01T12:30:05","modified_gmt":"2024-10-01T15:30:05","slug":"tras-la-ruptura-de-ioma-con-femeba-el-radicalismo-exige-respuestas-en-el-hcd","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2024\/10\/01\/tras-la-ruptura-de-ioma-con-femeba-el-radicalismo-exige-respuestas-en-el-hcd\/","title":{"rendered":"Tras la ruptura de IOMA con Femeba, el radicalismo \u201cexige respuestas\u201d en el HCD"},"content":{"rendered":"\n<p>Presentaron un proyecto de Comunicaci\u00f3n en el que convocaron a autoridades de salud locales y autoridades de IOMA. \u201cLos afiliados a IOMA son rehenes de una p\u00e9sima administraci\u00f3n desde hace a\u00f1os\u201d dijo Francisco Gonz\u00e1lez.<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p>Este martes, <strong>el bloque de la UCR present\u00f3 en el HCD un Proyecto de Comunicaci\u00f3n para convocar durante su tratamiento al Secretario de Salud Municipal, a representantes locales de IOMA y a autoridades del C\u00edrculo M\u00e9dico de Olavarr\u00eda, con el fin de conocer las implicancias de la situaci\u00f3n en Olavarr\u00eda luego de que IOMA prescindiera de las prestaciones de FEMEBA<\/strong> en algunos distritos de la Provincia, entre los que se encuentra nuestra ciudad.<\/p>\n\n\n\n<p>En los \u00faltimos d\u00edas se conoci\u00f3 la novedad de que <strong>a partir del 1\u00b0 de octubre los afiliados a IOMA no tendr\u00e1n cobertura de los servicios prestados por FEMEBA<\/strong>. <em>\u201cEsto genera un gran perjuicio para los afiliados, tanto a la hora de atenderse con distintos profesionales, como tambi\u00e9n en la parte econ\u00f3mica. Es un duro golpe para muchos vecinos\u201d<\/em>, se\u00f1al\u00f3 al respecto el concejal Francisco Gonzalez.<\/p>\n\n\n\n<p>Es por esto que en el d\u00eda de hoy <strong>el bloque de concejales present\u00f3 un Proyecto de Comunicaci\u00f3n donde convocan a las autoridades locales de IOMA para que informe sobre los motivos que llevaron a la obra social a finalizar el convenio con FEMEBA<\/strong>. Del mismo modo, solicitan la presencia del Secretario de Salud Municipal para que informe<strong> c\u00f3mo se prepara el sistema de salud local para absorber y contener a los afiliados de IOMA que se vean afectados por la interrupci\u00f3n del servicio prestacional.<\/strong><\/p>\n\n\n\n<p>Por \u00faltimo, <strong>piden convocar a autoridades del C\u00edrculo M\u00e9dico de Olavarr\u00eda para que expongan los efectos que tendr\u00e1n las medidas adoptadas por IOMA respecto a FEMEBA en la atenci\u00f3n m\u00e9dica local y qu\u00e9 acciones se llevar\u00e1n a cabo para mitigar el impacto en los afiliados de IOMA.<\/strong><\/p>\n\n\n\n<p><em>\u201cLos afiliados a IOMA son rehenes de una p\u00e9sima administraci\u00f3n desde hace a\u00f1os y ahora se ha llegado a un punto muy grave. En el d\u00eda de hoy son miles de vecinos que se encuentran sin ning\u00fan tipo de cobertura\u201d indic\u00f3 el edil radical. \u201cCirug\u00edas y tratamientos suspendidos, turnos cancelados, y no hay quien de respuesta ante tanta incertidumbre\u201d<\/em>, manifest\u00f3.<\/p>\n\n\n\n<p>Por su parte,<strong> la presidente de la UCR, Bel\u00e9n Vergel,<\/strong> declar\u00f3 que \u201c<em>nos preocupa la salud de nuestros vecinos, sus tratamientos, y la manera en que se ven afectados por una p\u00e9sima administraci\u00f3n que gestiona sobre pareceres pol\u00edticos y de espaldas a miles de afiliados. Como tambi\u00e9n las implicancias que esto tendr\u00e1 en todo el sistema sanitario p\u00fablico que actualmente presenta deficiencias, y si a esto le agregamos a los gran cantidad de vecinos que se atend\u00edan en consultorios privados con la cobertura de IOMA, realmente se aproxima un futuro muy complejo\u201d.<\/em><\/p>\n\n\n\n<p><em><strong>\u201cLa salud no puede esperar, necesita de una planificaci\u00f3n clara y contundente ante esta situaci\u00f3n. El contexto demanda respuestas y acciones r\u00e1pidas\u201d<\/strong><\/em>, finaliz\u00f3 Vergel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentaron un proyecto de Comunicaci\u00f3n en el que convocaron a autoridades de salud locales y autoridades de IOMA. \u201cLos afiliados<\/p>\n","protected":false},"author":2,"featured_media":90662,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,1],"tags":[],"class_list":["post-126785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/07\/vergel-pan3.jpg?fit=1109%2C617&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/126785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=126785"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/126785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/90662"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=126785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=126785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=126785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}