{"id":125882,"date":"2024-09-19T08:21:33","date_gmt":"2024-09-19T11:21:33","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=125882"},"modified":"2024-09-19T08:21:35","modified_gmt":"2024-09-19T11:21:35","slug":"norma-dora-del-zotto-de-barrionuevo-q-e-p-d","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2024\/09\/19\/norma-dora-del-zotto-de-barrionuevo-q-e-p-d\/","title":{"rendered":"Norma Dora Del Zotto de Barrionuevo (Q.E.P.D.)"},"content":{"rendered":"\n<p>Falleci\u00f3 en C.A.B.A el 18 de septiembre de 2024 a los 78 a\u00f1os de edad. Su esposo: M\u00e1ximo Barrionuevo; sus hijos Leonardo y Melisa Barrionuevo Del Zotto; sus hijos pol\u00edticos Fernanda y Dar\u00edo; sus nietos Uma, Ringo, Juana y Lara; sus hermanos Juan Carlos y Daniel Barrionuevo; sus hermanos pol\u00edticos, sobrinos y dem\u00e1s deudos participan su fallecimiento.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Sus restos ser\u00e1n velados en Espa\u00f1a 2942, departamento &#8220;F&#8221; (comienza 14:00, cierra 20:30 y reabre 8:00) y ser\u00e1n inhumados en el cementerio Loma de Paz, este viernes a las 9:30, previo responso en la capilla ardiente. Vecina de Microcentro. Nacida en Olavarr\u00eda. Jubilada Docente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Falleci\u00f3 en C.A.B.A el 18 de septiembre de 2024 a los 78 a\u00f1os de edad. Su esposo: M\u00e1ximo Barrionuevo; sus<\/p>\n","protected":false},"author":2,"featured_media":100390,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-125882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-necrologicas"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/10\/necrologicas-390-x-240.jpg?fit=390%2C240&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/125882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=125882"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/125882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/100390"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=125882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=125882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=125882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}