{"id":118396,"date":"2024-06-13T19:45:30","date_gmt":"2024-06-13T22:45:30","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=118396"},"modified":"2024-06-13T19:45:32","modified_gmt":"2024-06-13T22:45:32","slug":"el-teatro-municipal-recibe-a-patricia-sosa-en-su-nueva-gira","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2024\/06\/13\/el-teatro-municipal-recibe-a-patricia-sosa-en-su-nueva-gira\/","title":{"rendered":"El Teatro Municipal recibe a Patricia Sosa en su nueva gira"},"content":{"rendered":"\n<p>El show ser\u00e1 el jueves 22 de agosto y las entradas ya se encuentran a la venta.<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>Patricia Sosa vuelve a Olavarr\u00eda<\/strong> para presentar su \u201c<strong>Gira M\u00e1gica\u201d<\/strong>, con la cual visita distintos escenarios de nuestro pa\u00eds. El show ser\u00e1 el <strong>jueves 22 de agosto desde las 21:00 horas en el Teatro Municipal.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>El a\u00f1o pasado, Patricia Sosa cautiv\u00f3 a audiencias de todo el pa\u00eds con sus exitosas presentaciones en el Teatro \u00d3pera y el Luna Park, dejando una huella imborrable en cada espectador.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Con una voz que trasciende lo meramente audible y una presencia esc\u00e9nica que emana autenticidad, Sosa es m\u00e1s que una cantante: es una fuerza de la naturaleza, una artista completa que logra empatizar con su p\u00fablico en cada una de sus presentaciones en vivo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Patricia no s\u00f3lo cuenta con una voz que es su sello personal, sino que, adem\u00e1s tiene mucho para decir a trav\u00e9s de su arte, algo que con el tiempo le ha permitido forjar una s\u00f3lida trayectoria y un v\u00ednculo inquebrantable con su audiencia.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La cantante llegar\u00e1 a distintos escenarios acompa\u00f1ada por un <strong>conjunto de m\u00fasicos excepcionales<\/strong>, entre los que se encuentran Gustavo Giuliano en bajo, Pablo Garrocho en bater\u00eda y coros, Mariano Mere en teclados y coros, Cristian Vidal en guitarras y coros, y Marta Mediavilla en coros.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Seg\u00fan anticip\u00f3 la artista, \u201c<strong><em>este encuentro est\u00e1 pensado especialmente, para todos los que quieran compartir m\u00fasica, emociones, renovar la energ\u00eda del alma y descubrir la magia de la vida\u201d.<\/em><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Entrada general numerada en plateas y palcos<\/strong><\/p>\n\n\n\n<p>Venta en Tecnocentro (Rivadavia 3065) en efectivo: $ 27500 Platea baja- $ 22000 Platea alta- $ 19800 Pullman- $ 27500 Palcos Venta on line www.articket.com.ar con cr\u00e9dito y d\u00e9bito: $ 28750 Platea baja- $ 23000 Platea alta- $ 28750 Sillas de palcos- $ 20700 Pullman.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El show ser\u00e1 el jueves 22 de agosto y las entradas ya se encuentran a la venta. Patricia Sosa vuelve<\/p>\n","protected":false},"author":6,"featured_media":118397,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,1],"tags":[],"class_list":["post-118396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/06\/patricia-sosa.jpg?fit=900%2C540&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/118396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=118396"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/118396\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/118397"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=118396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=118396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=118396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}