{"id":115956,"date":"2024-05-12T18:34:13","date_gmt":"2024-05-12T21:34:13","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=115956"},"modified":"2024-05-12T18:34:15","modified_gmt":"2024-05-12T21:34:15","slug":"los-precios-de-los-agroalimentos-se-multiplicaron-por-35-veces-en-abril","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2024\/05\/12\/los-precios-de-los-agroalimentos-se-multiplicaron-por-35-veces-en-abril\/","title":{"rendered":"Los precios de los agroalimentos se multiplicaron por 3,5 veces en abril"},"content":{"rendered":"\n<p>As\u00ed fue reflejado en un informe de la Confederaci\u00f3n Argentina de la Mediana Empresa. El lim\u00f3n, la mandarina, la naranja, la pera y la carne de cerdo presentan mayores brechas entre productor y consumidor. <\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Seg\u00fan el \u00cdndice de Precios en Origen y Destino (IPOD) elaborado por el sector de Econom\u00edas Regionales de la Confederaci\u00f3n Argentina de la Mediana Empresa (CAME), en abril los precios de los agroalimentos se multiplicaron por 3,5 veces del campo (origen) a la g\u00f3ndola (destino). Es decir, el consumidor pag\u00f3 $3,5 por cada $1 que recibi\u00f3 el productor.<\/p>\n\n\n\n<p><br><br>En promedio,<strong> la participaci\u00f3n del productor explic\u00f3 el 31,4% de los precios de venta final. <\/strong>La mayor participaci\u00f3n la tuvieron los productores de frutilla (81%), mientras que la menor fue para los de lim\u00f3n (8,1%).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/unnamed-4.png?resize=800%2C445&#038;ssl=1\" alt=\"\" class=\"wp-image-115958\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/unnamed-4.png?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/unnamed-4.png?resize=300%2C167&amp;ssl=1 300w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/unnamed-4.png?resize=768%2C427&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p><br><br><strong>La brecha en los productos frutihort\u00edcolas y en los ganaderos<\/strong><\/p>\n\n\n\n<p><br><br><strong>IPOD frutihort\u00edcola: <\/strong>del campo a la g\u00f3ndola, los precios de las 19 frutas y hortalizas que integran la canasta IPOD se multiplicaron por 4,3 veces en abril, lo que representa una disminuci\u00f3n del 6,5% con respecto a marzo.<\/p>\n\n\n\n<p><br><br><strong>IPOD ganadero:<\/strong> por los 5 productos y subproductos ganaderos que componen la canasta IPOD, el consumidor abon\u00f3 3,2 veces m\u00e1s de lo que recibi\u00f3 el productor, un 3,3% m\u00e1s que el mes pasado.<\/p>\n\n\n\n<p><br><br>Cabe destacar que seg\u00fan el \u00cdndice de Ventas Minoristas de CAME, <strong>las ventas del rubro alimentos y bebidas acumulan una ca\u00edda del 23,8% en los primeros cuatro meses del a\u00f1o<\/strong> frente al mismo per\u00edodo de 2023, reflejo de la disminuci\u00f3n del poder adquisitivo y la falta de convalidaci\u00f3n de precios por parte del consumidor. Es decir, la baja se explica por una detracci\u00f3n de la demanda.  <\/p>\n\n\n\n<p><br><br>Adem\u00e1s, durante el primer cuatrimestre del a\u00f1o, todos los eslabones de las distintas cadenas de valor han visto afectada su rentabilidad por los<strong> fuertes incrementos de costos<\/strong>, no s\u00f3lo debido a la devaluaci\u00f3n, sino tambi\u00e9n al aumento del transporte y la log\u00edstica, luz, gas, patentes e impuesto inmobiliario, arrendamientos, combustibles, fertilizantes y repuestos de maquinarias, por citar algunos.<\/p>\n\n\n\n<p>. <br><br><strong>Mayores y menores brechas IPOD de abril<\/strong><\/p>\n\n\n\n<p><br><strong>Productos con mayores brechas IPOD mensuales<\/strong><\/p>\n\n\n\n<p><br>El lim\u00f3n (12,3 veces), la mandarina (6,9), la naranja (6,3), la pera (5,9) y la carne de cerdo (5,6) fueron los cinco productos que presentaron mayor diferencia entre los precios de origen y destino.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/unnamed-5.png?resize=800%2C445&#038;ssl=1\" alt=\"\" class=\"wp-image-115957\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/unnamed-5.png?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/unnamed-5.png?resize=300%2C167&amp;ssl=1 300w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/unnamed-5.png?resize=768%2C427&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p><br><br><strong><br>Productos con menores brechas IPOD mensuales<\/strong><\/p>\n\n\n\n<p><br>Los cinco productos que presentaron menor diferencia entre el precio que recibi\u00f3 el productor y el que pag\u00f3 el consumidor forman parte de la canasta frutihort\u00edcola. Se trata de la frutilla, la calabaza, la cebolla, el tomate redondo y el pimiento. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/unnamed-6.png?resize=800%2C445&#038;ssl=1\" alt=\"\" class=\"wp-image-115959\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/unnamed-6.png?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/unnamed-6.png?resize=300%2C167&amp;ssl=1 300w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/05\/unnamed-6.png?resize=768%2C427&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p><br><br><strong>El an\u00e1lisis demuestra que el productor primario no es formador de precios. <\/strong>Si bien algunos productos con alta incidencia en la canasta (como, por ejemplo, la cebolla y el tomate) presentaron un reacomodamiento en los precios al productor, estos valores no llegaron a compensar la inflaci\u00f3n acumulada, por lo que <strong>el primer eslab\u00f3n (origen-productor) sigue resignando rentabilidad frente al resto de los actores de la cadena de valor.<\/strong> Es decir, la estructura de formaci\u00f3n de precios en Argentina nace en la g\u00f3ndola y se va disgregando hacia atr\u00e1s, hasta llegar al productor, cuando deber\u00eda ser al rev\u00e9s.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed fue reflejado en un informe de la Confederaci\u00f3n Argentina de la Mediana Empresa. El lim\u00f3n, la mandarina, la naranja,<\/p>\n","protected":false},"author":2,"featured_media":101712,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,1],"tags":[],"class_list":["post-115956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/11\/DIB-mercado-verdura-precios.jpg?fit=696%2C464&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/115956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=115956"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/115956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/101712"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=115956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=115956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=115956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}