{"id":111720,"date":"2024-03-19T20:05:26","date_gmt":"2024-03-19T23:05:26","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=111720"},"modified":"2024-03-19T20:05:29","modified_gmt":"2024-03-19T23:05:29","slug":"nuevos-profesionales-en-la-facultad-de-ciencias-de-la-salud-2","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2024\/03\/19\/nuevos-profesionales-en-la-facultad-de-ciencias-de-la-salud-2\/","title":{"rendered":"Nuevos profesionales en la Facultad de Ciencias de la Salud"},"content":{"rendered":"\n<p>Este s\u00e1bado, 24 profesionales se egresaron de la carrera de medicina luego de realizar una evaluaci\u00f3n de la Pr\u00e1ctica Final Obligatoria (PFO).<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p>Este s\u00e1bado se llev\u00f3 a cabo una nueva <strong>evaluaci\u00f3n de la Pr\u00e1ctica Final Obligatoria (PFO) <\/strong>en instalaciones del Hospital Municipal \u201cDr. H\u00e9ctor Cura\u201d y los laboratorios de la Facultad de Ciencias de la Salud.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En esta oportunidad <strong>fueron 24 las y los encargados de convertirse en nuevos y nuevas profesionales de la carrera de medicina<\/strong> <strong>de la Facultad de Ciencias de la Salud <\/strong>de la Universidad Nacional del Centro de la Provincia de Buenos Aires.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Las y los nuevos profesionales: Aguero Lourdes, Guzm\u00e1n Abril Naiara, Baudriz Francisco, Bonifacio Micaela, Ondicola Agustina, Campo Melanie, Capandegui Julieta, Citati Horacio, Lafuente Luz Belen, Curcio Louge Antonella, Gonzalez Anah\u00ed, De Martino Camila, Pavioni Palma Neliam Anaeli, Silva Lucrecia, Fernandez Daiana Rocio, Giangreco Sebastian Danilo, Gil Agustin, Golotylec Manuela, Gomez Merlos Camila, Dal Poggetto Pierina, Guindo Pilar Mar\u00eda, Ayala Jennifer, Heht Mat\u00edas y Herrera Victoria Abril.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/03\/nuevos-profesionales-salud-1.jpeg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-111722\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/03\/nuevos-profesionales-salud-1.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/03\/nuevos-profesionales-salud-1.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/03\/nuevos-profesionales-salud-1.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/03\/nuevos-profesionales-salud-1.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Las y los estudiantes fueron <strong>evaluados por profesionales de la salud <\/strong>mediante el sistema ECOE (Examen Cl\u00ednico Objetivo Estructurado). El ECOE est\u00e1 dise\u00f1ado para realizar una evaluaci\u00f3n del examen cl\u00ednico, de forma objetiva y estructurada, poniendo \u00e9nfasis en un eje muy importante, el hecho de evaluar las competencias profesionales de los futuros m\u00e9dicos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En este tipo de examen se eval\u00faa en forma integrada los conceptos te\u00f3ricos, las habilidades y destrezas cl\u00ednicas y las actitudes ante una situaci\u00f3n o problema cl\u00ednico. El ECOE cuenta con la presencia de actores y actrices guionados para cada una de las estaciones y consultorios.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En esta oportunidad, debido a la importante cantidad de inscriptos e inscriptas, se eligieron dos escenarios, el Hospital Municipal y la Facultad de Ciencias de la Salud. El pr\u00f3ximo s\u00e1bado, ser\u00e1n 25 los y las estudiantes que rendir\u00e1n el ECOE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este s\u00e1bado, 24 profesionales se egresaron de la carrera de medicina luego de realizar una evaluaci\u00f3n de la Pr\u00e1ctica Final<\/p>\n","protected":false},"author":6,"featured_media":111721,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-111720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/03\/nuevos-profesionales-salud-2.jpeg?fit=869%2C576&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/111720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=111720"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/111720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/111721"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=111720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=111720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=111720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}