{"id":107117,"date":"2024-01-19T17:10:28","date_gmt":"2024-01-19T20:10:28","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=107117"},"modified":"2024-01-19T17:10:30","modified_gmt":"2024-01-19T20:10:30","slug":"bancarios-acuerdan-un-salario-inicial-de-mas-de-900-mil-pesos","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2024\/01\/19\/bancarios-acuerdan-un-salario-inicial-de-mas-de-900-mil-pesos\/","title":{"rendered":"Bancarios acuerdan un salario inicial de m\u00e1s de 900 mil pesos"},"content":{"rendered":"<p>El acuerdo fue de 23,2% de incremento retroactivo a diciembre. El gremio adem\u00e1s ratific\u00f3 el paro y movilizaci\u00f3n del 24 de este mes hacia el Congreso.<\/p>\n<p><!--more--><\/p>\n<hr \/>\n<p>El <strong>gremio de los bancarios<\/strong> alcanz\u00f3 un <strong>acuerdo con las c\u00e1maras empresarias del sector<\/strong>, mediante el cual debe incorporarse a los salarios de diciembre una <strong>actualizaci\u00f3n del 23,2%, retroactivo al 1 de dicho mes<\/strong>, tomando la base de salarios de diciembre 2022. La misma aplica sobre todas las remuneraciones y adicionales convencionales y no convencionales.<\/p>\n<p>A su vez, sobre la base resultante a diciembre 2023, se acord\u00f3<strong> incorporar un 20% de adelanto para enero de este 2024<\/strong>. <em>El aumento de este primer mes es en concepto de adelanto, ya que de superar la inflaci\u00f3n el 20%, se ajustar\u00e1 autom\u00e1ticamente<\/em>, debiendo las entidades bancarias aplicar la diferencia salarial retroactiva que corresponda.<\/p>\n<blockquote><p>As\u00ed, el salario m\u00ednimo inicial bancario quedar\u00e1 compuesto de la siguiente manera: salario inicial m\u00e1s participaci\u00f3n en ganancias (ROE): enero $ 865.277,01 m\u00e1s $ 39.080,67, llega a un total de $ 904.357,68.<\/p><\/blockquote>\n<p>Por otro lado, el gremio que lidera Sergio Palazzo adem\u00e1s <strong>ratific\u00f3 el paro y movilizaci\u00f3n del 24 de este mes hacia el Congreso en rechazo del Decreto de Necesidad y Urgencia (DNU) y la Ley \u201cBases\u201d que el Gobierno envi\u00f3 al Parlamento<\/strong>, y tambi\u00e9n repudi\u00f3 la posibilidad de que el Ejecutivo decida privatizar el Banco de la Naci\u00f3n Argentina (BNA) y sus empresas vinculadas BICE y Casa de Moneda.<\/p>\n<p>Fuente: <em>Agencia DIB<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El acuerdo fue de 23,2% de incremento retroactivo a diciembre. El gremio adem\u00e1s ratific\u00f3 el paro y movilizaci\u00f3n del 24<\/p>\n","protected":false},"author":4,"featured_media":107118,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,1],"tags":[],"class_list":["post-107117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2024\/01\/Sergio-Palazzo-La-Bancaria-bancos.jpg?fit=863%2C479&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/107117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=107117"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/107117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/107118"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=107117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=107117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=107117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}