{"id":104702,"date":"2023-12-19T11:13:48","date_gmt":"2023-12-19T14:13:48","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=104702"},"modified":"2023-12-21T12:30:53","modified_gmt":"2023-12-21T15:30:53","slug":"este-jueves-se-realizara-un-importante-acto-de-firma-de-escrituras","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2023\/12\/19\/este-jueves-se-realizara-un-importante-acto-de-firma-de-escrituras\/","title":{"rendered":"Este jueves se realizar\u00e1 un importante acto de firma de escrituras"},"content":{"rendered":"\n<p>Ser\u00e1 este jueves desde las 11 en el club Pueblo Nuevo. Se lleva adelante tras el trabajo del Municipio, la Escriban\u00eda General de Gobierno y el Instituto de la Vivienda provincial.<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p>El Gobierno Municipal,<strong> la Escriban\u00eda General de Gobierno y el Instituto de la Vivienda de la Provincia de Buenos Aires contin\u00faan trabajando de manera conjunta para que m\u00e1s familias accedan a la escritura de su vivienda.<\/strong><\/p>\n\n\n\n<p>En ese marco, <strong>este jueves 21 de diciembre, a partir de las 11 horas, se llevar\u00e1 a cabo un nuevo acto de firma en el sal\u00f3n del club Pueblo Nuevo, ubicado sobre la esquina de Chacabuco y Necochea.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Se firmar\u00e1n 252 t\u00edtulos de propiedad, de los cuales 206 corresponden a la Ley 10.830, mientras que los 46 restantes a la operatoria del Instituto de la Vivienda.<\/p>\n<\/blockquote>\n\n\n\n<p><strong>Las personas mencionadas a continuaci\u00f3n deber\u00e1n concurrir a las 10:30 para su acreditaci\u00f3n. <\/strong>Deber\u00e1n presentar documento de identidad y fotocopia del mismo, constancias de CUIL\/CUIT, en caso de estar divorciados copia simple de la sentencia de divorcio, y en caso de presentarse en car\u00e1cter de apoderado\/a presentar el poder original.<\/p>\n\n\n\n<p><strong>Por m\u00e1s informaci\u00f3n o consultas dirigirse a la Direcci\u00f3n de Casa de Tierras y Regulaci\u00f3n Dominial, ubicada en Rivadavia N\u00b0 2861 (Palacio Municipal), o v\u00eda telef\u00f3nica al 440442 int. 1750-1753, en el horario de 7.30 a 12.30 horas.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Citaci\u00f3n<\/p>\n\n\n\n<p>Acosta, Diego Ra\u00fal \/\/ Acosta, N\u00e9stor Daniel \u2013 Santellan, Edda Esther \/\/ Acosta, Walter \u2013 Luna, Aldo Dar\u00edo \u2013 Pagano, Natalia Paola \/\/ Agapito, Jorge Paulo \u2013 Rekofski, Mar\u00eda De Los \u00c1ngeles \/\/ Aguer, M\u00f3nica Beatriz \/\/ Alba, Sonia Noemi \u2013 Navarro, Ruben Omar \/\/ Alfaro, Tamara Soledad \u2013 Camalbide, Gustavo Adri\u00e1n \/\/ Alfonzo, Gisela Fanny \u2013 Di Martino, Carlos Omar \/\/ Altamira, Stella Maris \/\/ \u00c1lvarez, Liliana Alejandra \u2013 Rivas, Sergio Fabi\u00e1n \/\/ \u00c1lvarez, Marcelo Fabi\u00e1n \u2013 Madrid, Marisa Lorena \/\/ \u00c1lvarez, Mar\u00eda Consuelo \/\/ Aqueveque, Alejandra Susana \u2013 Castro, N\u00e9stor Edgardo \/\/ Aramburu, Maria Lidia \u2013 Shmal, Adriana Graciela \/\/ Aravena Arcurio, Diego Sa\u00fal \u2013 Hermle, Laura Estela \u2013 Paulo, Yesica Soledad \/\/ Ar\u00e9valo, Sandra Ana Paula \/\/ Arhancetbehere, I\u00f1aki \u2013 L\u00f3pez, Silvia Beatriz -Arhancetbehere, Gustavo Ernesto \/\/ Aroca, Claudia Beatriz \u2013 Ramos, Omar Jose \/\/ Arrieta, Silvana Vanesa \/\/ Artaza, Marina Gabriela \u2013 Artaza, N\u00e9stor Arsenio \u2013 Pinelli, Ana Mar\u00eda \/\/ Avalos, Daiana Jaqueline \u2013 Castelli, Juan Carlos \/\/ Avila, Antonella Ayelen \/\/ Ayala, Javier Alberto \u2013 Cappelletti, Silvina Andrea \/\/ Bahl, Luis Florentino \u2013 Wagner, Beatriz Etel \/\/ Balmaceda, Angelica Liliana \/\/ Barbieri, Maria Jose \/\/ Barbosa, Miguel Leonardo \u2013 Pereyra, Franco Roberto \/\/ Barcelonna, Mirta Alejandra \u2013 Iglesias, Juan Carlos \/\/ Bargas, Luisa Mabel \/\/ Baumann, Hector Fabian \u2013 Chavez, Patricia Andrea \/\/ Becker, Mariangeles \u2013 Carlucci, Nicolas Alejandro \/\/ Belo, Mario Daniel \/\/ Beriay, Jorge Ricardo \u2013 Beriay, Mario Oscar \u2013 D\u00edaz, Mar\u00eda Yolanda \u2013 Legran, Noelia Natacha \u2013 Rivero, Yanina Soledad \/\/ Braun, Marcelo Alejandro \u2013 Lanezan, Mariana Jorgelina \/\/ Bucciarelli, Luis Horacio \u2013 Di Pizio, Mirta Liliana \/\/ Buchanan, Daiana Gisele \u2013 Vallades, Carlos Alberto \/\/ Buey, Marcos Mario \u2013 Minnig, Karina Noemi \/\/ Burelli, Carolina Gisele \u2013 Villamayor, Rodrigo Salvador \u2013 Martinefsky, Gladys Herminda \/\/ Bustos, Enrique Saturnino \u2013 Sosa, Andrea Fabiana \/\/ Campos, Saul Armando \u2013 Cortes, Evelyn Yamila \/\/ Ca\u00f1al, Yamila Eliana \u2013 D\u2019Onofrio, Enrique Javier \/\/ Carboni, Alberto Ruben \u2013 S\u00e1nchez, Anal\u00eda Mariel \u2013 Coronel, N\u00e9stor Omar \/\/ Caro, Norma Beatriz \u2013 Gomez, Marcelo Gustavo \/\/ Cepeda, Maria Celeste \/\/ Chaparro, Rodolfo Mario \u2013 Moser, Marianela \/\/ Chevrot, Lucas Ramiro \u2013 Martinez, Lilia Mabel \u2013 Scipioni, Guillermo Oscar \/\/ Cocuzza, Mar\u00eda Gabriela \u2013 Gabica, Gustavo Gabriel \/\/ Comensoli, Lucas Sebastian \u2013 Rodriguez Pereira, Vanes Isabel \/\/ Contreras, Marina Ivana \/\/ Coronel, Carlos Alberto \/\/ Cueto, Silvina Yesica Daniela \u2013 Sanchez, Manuel Alejandro \/\/ D\u2019Agostino, Francisco Humberto \u2013 D\u2019Agostino, Karina Ester \/\/ D\u2019Agostino, Francisco Humberto \u2013 D\u2019Agostino, Karina Ester \/\/ Degirolmo, Mirta Viviana \u2013 Vidal, Jose Marcos \/\/ Della Maggiora, Jose Pedro \u2013 Striebeck, Romina Ester \/\/ Desiderio, Jos\u00e9 Luis \/\/ Dufau, Delia Isabel \u2013 Fuentes, Julio Alberto \/\/ Emiliozzi, Jimena \/\/ Erdocia, Juan Pablo \u2013 Ferrero, Lucrecia Ivana \/\/ Fern\u00e1ndez, Dar\u00edo Sebasti\u00e1n \u2013 Pi\u00f1ero, Marilina Elisabet \/\/ Ferreyra, Mar\u00eda Laura \/\/ Franco, Norma Beatriz \/\/ Fredes, Ernesto Carlos \u2013 Perez, Claudia Isabel \/\/ Freites, Maria Florencia \/\/ Fuccila, Yanina Soledad \u2013 Roman, Alberto Andres \u2013 Robledo, Ruben Adolfo \/\/ Gallo, Jorge Raul \/\/ Gallo, Lorena Andrea \u2013 Medina, Ruben Edgardo \/\/ Gilez, Martina Gabina \u2013 Raccaro, Stella Maris \/\/ Ginter, Cristina De Los Angeles \u2013 Ginter, Gabriel Gerardo \u2013 Zentrigen, Norma Margarita \/\/ Gosio, Monica Marcela Edith \/\/ Gutierrez, Andrea Lucrecia \/\/ Hatte, Mariela Soledad \u2013 Hatte, Yanina Natalia \/\/ Heinrich, Maria Fernanda \u2013 Civitas Administradora De Circulos De Vivienda \/\/ Herr, Patricia Fabiana \u2013 Mattioli, Veronica Daniela \u2013 Vallejo, Mauro Oscar \/\/ Hohl, Griselda Beatriz \u2013 Juarez, Mirta Nelida \/\/ Iribe Rizzonelli, Edith Mabel \/\/ Iturregui, Maria Gabriela \u2013 Laurenz, Otto Omar \/\/ Izzi, Maria Fernanda \u2013 Revainera, Pedro Luis \/\/ Jaime, Romina Andrea \u2013 Montiel, Nicolas \/\/ Janson, Silvia Marcela \u2013 Sierra, Carolina Rosana \/\/ Ju\u00e1rez, Esteban Damian Ezequiel \/\/ La Spina, Guillermo Martin \u2013 Nazabal, Viviana Lorena \/\/ Lardapide, Osvaldo Ulises \u2013 Sosa, Silvana Sara \/\/ Leon, Juan Gustavo (V.) \u2013 Pasquini, Sandra Edith \u2013 Leon, Juan Ignacio \/\/ Lobos, Marcela Carina \/\/ Lora, Nelida Felisa \/\/ Lora, Rosa Graciela \u2013 Osinaga, Carlos Haroldo \/\/ Madue\u00f1a Abdala, Maria Celeste \u2013 Montoya Carlotto, Ignacio \/\/ Magallanes, Sergio Antonio \/\/ Magari\u00f1os, Carolina Fabiana \/\/ Marin,Marcela Alejandra \u2013 Marti,Nicolas Federico \/\/ Martinez, Laura Andrea \/\/ Martinez, Ruben Ezequiel \/\/ Matos, Enrique Norberto \u2013 Orsatti, Emilce Susana \u2013 Catanzaro, Hugo Adalberto \/\/ Matos, Stella Maris \u2013 Sanchez, Carlos Daniel \/\/ Mendiola, Joana Soledad \u2013 Orona, Nicolas Alejandro \/\/ Meza, Susana Beatriz \/\/ Miguel, Ricardo Alberto \/\/ Mi\u00f1o, Gloria Beatriz Del Carmen \/\/ Nievas, Silvia Anahi \u2013 Ruiz, Joel Antonio \/\/ Nu\u00f1ez, Mauricio Alejandro Matias \u2013&nbsp; Segura, Romina Soledad \/\/ Pe\u00f1alva, Carlos Alberto \u2013 Yungblut, Norma Liliana \/\/ Peralta, Valeria Norma \/\/ Persico, Maria Catalina \/\/ Pibuel, Cristian Daniel \u2013 Pibuel, Romina Soledad \/\/ Pinto, Cirila \/\/ Quinteros, Jose \/\/ Riveros, Roberto Manuel \u2013 Safenreider, Liliana Elisa \/\/ Rocha, Lucas Maximiliano \u2013 Rodriguez, Ayelen Rocio \/\/ Rodriguez, Carmen Gloria \/\/ Roman, Alejandro Sergio \/\/ Rosende, Luis Alberto \u2013 Trstenjak,Gladys Liliana \/\/ Rubio, Elena Mabel \/\/ Ruiz Diaz, Liliana Raquel \u2013 Ureta, Raul Marcelo \/\/ Sabec, Silvana Graciela \u2013 Veron, Nazario Felix \/\/ Sanchez, Estela Mabel \u2013 Tambucci, Humberto Daniel \/\/ Suarez, Natalia Estefania \/\/ Tagliaferro, Maria Rosa \u2013 Vallejos, Antonio Jesus \/\/ Tinta, Claudia Marisa \/\/ Valdez, Lorenzo Agustin \u2013 Valdez, Ignacio \u2013 Cometta, Maria Raquel \/\/ Van Dyk, Omar Alfredo \/\/ Vicente, Sandra Edith \/\/ Villegas, Omar Alejandro \/\/ Wilwert, Angel Juan \u2013 Zarate, Marta Elena \/\/ Ya\u00f1ez, Hugo Enrique .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 este jueves desde las 11 en el club Pueblo Nuevo. Se lleva adelante tras el trabajo del Municipio, la<\/p>\n","protected":false},"author":2,"featured_media":104704,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-104702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/12\/escrituras.jpg?fit=1024%2C685&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/104702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=104702"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/104702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/104704"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=104702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=104702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=104702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}