{"id":104600,"date":"2023-12-18T10:12:45","date_gmt":"2023-12-18T13:12:45","guid":{"rendered":"https:\/\/cdnoticias.com\/?p=104600"},"modified":"2023-12-18T13:09:47","modified_gmt":"2023-12-18T16:09:47","slug":"temporal-en-olavarria-el-sector-horticola-tuvo-perdidas-estimadas-en-50-millones-de-pesos","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2023\/12\/18\/temporal-en-olavarria-el-sector-horticola-tuvo-perdidas-estimadas-en-50-millones-de-pesos\/","title":{"rendered":"Temporal en Olavarr\u00eda: el sector hort\u00edcola tuvo p\u00e9rdidas estimadas en 50 millones de pesos"},"content":{"rendered":"<p>Lo inform\u00f3 la Federaci\u00f3n Rural que detall\u00f3 da\u00f1os en la producci\u00f3n y en instalaciones.\u00a0Advirti\u00f3 adem\u00e1s por el \u201criesgo de quiebra de los productores hort\u00edcolas\u201d y el potencial desabastecimiento.<\/p>\n<p><!--more--><\/p>\n<hr \/>\n<p>Desde la <strong>Federaci\u00f3n Rural y UTEP<\/strong> se inform\u00f3 el <strong>impacto de la condiciones clim\u00e1ticas<\/strong> de la semana pasada en el <strong>sector hort\u00edcola de Olavarr\u00eda<\/strong>: serios da\u00f1os sufri\u00f3 la producci\u00f3n as\u00ed como las instalaciones que <strong>se evaluaron en millones de pesos en costos<\/strong>.<\/p>\n<p>\u201cDurante el temporal del martes 12 de diciembre se registraron fuertes r\u00e1fagas de viento, granizo e intensas lluvias que afectaron a toda la ciudad y tuvo <strong>fuerte impacto en el sector de la agricultura familiar principalmente en la producci\u00f3n de verduras y hortalizas<\/strong>\u201d se indic\u00f3.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-104601 aligncenter\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/12\/sector-horticola-temporal-02.jpg?resize=800%2C445&#038;ssl=1\" alt=\"\" width=\"800\" height=\"445\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/12\/sector-horticola-temporal-02.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/12\/sector-horticola-temporal-02.jpg?resize=300%2C167&amp;ssl=1 300w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/12\/sector-horticola-temporal-02.jpg?resize=768%2C427&amp;ssl=1 768w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/12\/sector-horticola-temporal-02.jpg?resize=800%2C445&amp;ssl=1 800w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<blockquote><p>La entidad detall\u00f3 que \u201croturas de invernaderos, p\u00e9rdida completa y parcial de la producci\u00f3n (alrededor de 20 variedades), quintas inundadas fue lo que qued\u00f3 despu\u00e9s del temporal. Esta situaci\u00f3n gener\u00f3 p\u00e9rdidas productivas: las variedades de estaci\u00f3n que permiten generar ganancia durante la temporada de verano fueron destruidas casi en su totalidad esto genera dos grandes problemas, la escasez para el abastecimiento local pero tambi\u00e9n el riesgo de quiebra de los productores hort\u00edcolas ya que es con esta ganancia es como sostienen los alquileres en las temporadas menos favorables. Estas p\u00e9rdidas reflejan alrededor de 50 millones de pesos que de no ser acompa\u00f1adas por el estado estas familias corren el riesgo de endeudarse o \u00b4quebrar\u00b4\u201d.<\/p><\/blockquote>\n<p>Federaci\u00f3n Rural record\u00f3 que \u201ctoda la producci\u00f3n de la agricultura familiar es de consumo interno por lo que a su vez <strong>la no intervenci\u00f3n inmediata por parte del estado podr\u00eda provocar el desabastecimiento local de verduras y hortalizas<\/strong> (que repercute en un aumento de precios) en un momento de crisis econ\u00f3mica\u201d.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-104602 aligncenter\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/12\/sector-horticola-temporal-00.jpg?resize=800%2C445&#038;ssl=1\" alt=\"\" width=\"800\" height=\"445\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/12\/sector-horticola-temporal-00.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/12\/sector-horticola-temporal-00.jpg?resize=300%2C167&amp;ssl=1 300w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/12\/sector-horticola-temporal-00.jpg?resize=768%2C427&amp;ssl=1 768w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/12\/sector-horticola-temporal-00.jpg?resize=800%2C445&amp;ssl=1 800w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo inform\u00f3 la Federaci\u00f3n Rural que detall\u00f3 da\u00f1os en la producci\u00f3n y en instalaciones.\u00a0Advirti\u00f3 adem\u00e1s por el \u201criesgo de quiebra<\/p>\n","protected":false},"author":4,"featured_media":104603,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-104600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/12\/sector-horticola-temporal-01.jpg?fit=1000%2C556&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/104600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=104600"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/104600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/104603"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=104600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=104600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=104600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}