{"id":10393,"date":"2021-01-01T10:29:56","date_gmt":"2021-01-01T13:29:56","guid":{"rendered":"http:\/\/www.centraldenoticias.com.ar\/?p=10393"},"modified":"2021-01-01T10:29:56","modified_gmt":"2021-01-01T13:29:56","slug":"la-madrid-dio-positivo-de-covid19-y-fue-sorprendido-en-la-calle","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2021\/01\/01\/la-madrid-dio-positivo-de-covid19-y-fue-sorprendido-en-la-calle\/","title":{"rendered":"La Madrid: Dio positivo de Covid19 y fue sorprendido en la calle"},"content":{"rendered":"<p>Tiene 46 a\u00f1os y ahora afronta una causa Federal. El municipio vecino se encuentra en el pico de casos desde el inicio de la pandemia.<\/p>\n<p><!--more--><\/p>\n<hr \/>\n<p>General La Madrid es uno de los distritos de la regi\u00f3n que m\u00e1s ha visto complicar su situaci\u00f3n en el transcurso de las \u00faltimas semanas. D\u00edas atr\u00e1s el Intendente, quien recientemente <a href=\"https:\/\/cdnoticias.com\/index.php\/2020\/12\/28\/covid19-en-la-region-por-contacto-estrecho-aislaron-al-intendente-de-general-la-madrid\/\" target=\"_blank\" rel=\"noopener\">debi\u00f3 aislarse por un contacto estrecho<\/a>, lider\u00f3 <a href=\"https:\/\/cdnoticias.com\/index.php\/2020\/12\/23\/general-la-madrid-se-triplicaron-los-casos-en-un-mes\/\" target=\"_blank\" rel=\"noopener\">una conferencia de prensa en la que llam\u00f3 a la comunidad a reforzar los cuidados ante el avance del virus<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Sin embargo, un hombre de 46 a\u00f1os en las \u00faltimas horas hizo todo lo contrario, seg\u00fan detallan medios period\u00edsticos de la vecina ciudad. De acuerdo a lo narrado, <strong>personal policial lo sorprendi\u00f3 en la calle cuando deb\u00eda estar aislado en su casa tras haber dado positivo de Coronavirus.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10395\" src=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2021\/01\/01.jpg?resize=743%2C450&#038;ssl=1\" alt=\"\" width=\"743\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2021\/01\/01.jpg?w=743&amp;ssl=1 743w, https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2021\/01\/01.jpg?resize=300%2C182&amp;ssl=1 300w\" sizes=\"auto, (max-width: 743px) 100vw, 743px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ahora afronta una causa con intervenci\u00f3n de la Justicia Federa<\/strong>l, m\u00e1s precisamente el doctor Santiago Eyherabide, de la Fiscal\u00eda Federal de Tandil, dependiente del Departamento Judicial Azul.<\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan el parte oficial emitido en las \u00faltimas horas,<strong> La Madrid registr\u00f3 6 nuevos casos positivos, lo que elev\u00f3 a 66 el n\u00famero de casos activos, cifra que representa m\u00e1s de un tercio de los casos que la comuna registr\u00f3 durante toda la pandemia<\/strong>. A la par, aguarda por el resultado de 60 hisopados.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Con informaci\u00f3n y fotos de Info GL<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tiene 46 a\u00f1os y ahora afronta una causa Federal. El municipio vecino se encuentra en el pico de casos desde<\/p>\n","protected":false},"author":3,"featured_media":9065,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,1],"tags":[],"class_list":["post-10393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2020\/12\/la-madrid.jpg?fit=637%2C354&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/10393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=10393"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/10393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/9065"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=10393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=10393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=10393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}