{"id":10384,"date":"2021-01-01T09:22:39","date_gmt":"2021-01-01T12:22:39","guid":{"rendered":"http:\/\/www.centraldenoticias.com.ar\/?p=10384"},"modified":"2021-01-01T09:22:39","modified_gmt":"2021-01-01T12:22:39","slug":"florentino-belisle-cholo-q-e-p-d","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2021\/01\/01\/florentino-belisle-cholo-q-e-p-d\/","title":{"rendered":"Florentino Belisle  &#8220;Cholo&#8221;  (Q.E.P.D.)"},"content":{"rendered":"<p>Falleci\u00f3 en Olavarr\u00eda el d\u00eda 1 de Enero de 2021 a los 79 a\u00f1os de edad. Su esposa N\u00e9lida Aravena; sus hijos: Carlos y Gustavo Belisle y dem\u00e1s deudos participan su fallecimiento.<\/p>\n<p>&nbsp;<\/p>\n<p>Sus restos ser\u00e1n velados este s\u00e1bado 2 de enero desde las 8.30 y ser\u00e1n inhumados a las 10.30 en el cementerio Loma de Paz, servicio adherido a Coopelectric.<\/p>\n<p>&nbsp;<\/p>\n<p>Nacido en R\u00edo Negro, vecino del barrio Jard\u00edn, comerciante Jubilado. Ex acomodador del Cine Olavarr\u00eda.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Falleci\u00f3 en Olavarr\u00eda el d\u00eda 1 de Enero de 2021 a los 79 a\u00f1os de edad. Su esposa N\u00e9lida Aravena;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-10384","post","type-post","status-publish","format-standard","hentry","category-necrologicas"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/10384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=10384"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/10384\/revisions"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=10384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=10384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=10384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}