{"id":100017,"date":"2023-10-23T10:57:26","date_gmt":"2023-10-23T13:57:26","guid":{"rendered":"https:\/\/www.centraldenoticias.com.ar\/?p=100017"},"modified":"2023-10-23T14:48:28","modified_gmt":"2023-10-23T17:48:28","slug":"valicenti-la-riqueza-de-la-politica-es-convivir-con-aquel-que-piensa-distinto","status":"publish","type":"post","link":"https:\/\/cdnoticias.com\/index.php\/2023\/10\/23\/valicenti-la-riqueza-de-la-politica-es-convivir-con-aquel-que-piensa-distinto\/","title":{"rendered":"Valicenti: \u201cla riqueza de la pol\u00edtica es convivir con aquel que piensa distinto\u201d"},"content":{"rendered":"<p>El diputado provincial destac\u00f3 el di\u00e1logo como valor fundamental de la nueva gesti\u00f3n. Los desaf\u00edos y su rol a futuro. <!--more--><\/p>\n<hr \/>\n<p>El <strong>diputado provincial C\u00e9sar Valicenti<\/strong> habl\u00f3 con <em>Central de Noticias<\/em> luego de conocerse la <a href=\"https:\/\/cdnoticias.com\/index.php\/2023\/10\/22\/hay-algo-nuevo-que-nos-abraza-a-todos-y-es-una-mejor-olavarria\/\" target=\"_blank\" rel=\"noopener\">victoria de Uni\u00f3n por la Patria a nivel local por m\u00e1s del 41% de los votos.<\/a> \u201cEvidentemente hab\u00eda algo que estaba despertando, que <strong>lo despert\u00f3 Maxi<\/strong>\u201d se\u00f1al\u00f3 y agreg\u00f3: \u201ctambi\u00e9n se ve ac\u00e1 una expresi\u00f3n que supera una elecci\u00f3n\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>En ese sentido, destac\u00f3 la alegr\u00eda de las personas que se acerc\u00f3 a festejar el triunfo del nuevo intendente de la ciudad con \u201chay ganas de sentirse representados de un sector muy importante de la ciudad\u201d. Adem\u00e1s, reconoci\u00f3 que <strong>\u201clos desaf\u00edos y las responsabilidades hacia adelante son enormes, estamos contentos y a su vez cargados de un gran compromiso\u201d.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Destac\u00f3 la heterogeneidad del espacio de Uni\u00f3n por la Patria.<\/strong> \u201cSiempre lo fuimos, intentaron construir un estigma de la figura de muchos de nosotros, pero no paramos de hablar siempre con todo el mundo\u201d. Esto, seg\u00fan Valicenti, demostr\u00f3 que \u201cno solamente somos capaces de hablar con quienes piensen iguales. La riqueza de la pol\u00edtica es convivir con aquel que piensa distinto, es la riqueza de las sociedades, de las ideas\u201d.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u201cMaxi es una s\u00edntesis de eso y por supuesto que en un futuro gobierno la gesti\u00f3n tiene que llevar esa impronta, la capacidad de hablar con todos los sectores, con las instituciones que te responden pol\u00edticamente, pero con la que no te responden pol\u00edticamente. No excluir, sino llamar, convocar, trabajar por la ciudad\u201d, se\u00f1al\u00f3 Valicenti.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>Por \u00faltimo, expres\u00f3 respecto al<strong> fin de su mandato como diputado y el rol que ocupar\u00e1 dentro de la nueva gesti\u00f3n<\/strong> que \u201csoy un militante y donde me toque estar voy a acompa\u00f1ar con toda la fuerza\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Resalt\u00f3 que \u201cmuchas veces quienes piensan la pol\u00edtica de una manera reducida creen que para ejercer una responsabilidad ten\u00e9s que tener un cargo institucional y la verdad que<strong> nosotros siempre hemos militado de la misma manera, con grandes responsabilidades institucionales y sin responsabilidades institucionales<\/strong>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"1ctPUrJrJ9\"><p><a href=\"https:\/\/cdnoticias.com\/index.php\/2023\/10\/22\/hay-algo-nuevo-que-nos-abraza-a-todos-y-es-una-mejor-olavarria\/\">\u201cHay algo nuevo que nos abraza a todos y es una mejor Olavarr\u00eda\u201d<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;\u201cHay algo nuevo que nos abraza a todos y es una mejor Olavarr\u00eda\u201d&#8221; &#8212; Central de Noticias | Olavarr\u00eda\" src=\"https:\/\/cdnoticias.com\/index.php\/2023\/10\/22\/hay-algo-nuevo-que-nos-abraza-a-todos-y-es-una-mejor-olavarria\/embed\/#?secret=XnztcA7ToS#?secret=1ctPUrJrJ9\" data-secret=\"1ctPUrJrJ9\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El diputado provincial destac\u00f3 el di\u00e1logo como valor fundamental de la nueva gesti\u00f3n. Los desaf\u00edos y su rol a futuro.<\/p>\n","protected":false},"author":1,"featured_media":100020,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,1],"tags":[],"class_list":["post-100017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-portada"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cdnoticias.com\/wp-content\/uploads\/2023\/10\/wesner-festejos-10-1.jpg?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/100017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=100017"}],"version-history":[{"count":0,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/100017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media\/100020"}],"wp:attachment":[{"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=100017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=100017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=100017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}